{"id":36610,"date":"2026-03-18T16:51:59","date_gmt":"2026-03-18T16:51:59","guid":{"rendered":"https:\/\/transformiran.com\/unkategorisiert\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/"},"modified":"2026-06-09T02:43:56","modified_gmt":"2026-06-09T01:43:56","slug":"tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation","status":"publish","type":"post","link":"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/","title":{"rendered":"Tech-Interview mit Pulse 2.0: Glaubensbasierter Einsatz und Innovation"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Von Amit Chowdhry<\/p>\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Transform Iran ist ein christlicher Dienst, der sich zum Ziel gesetzt hat, die iranische Gesellschaft zu ver\u00e4ndern, indem er Untergrundgemeinden gr\u00fcndet, F\u00fchrungskr\u00e4fte ausbildet und das Evangelium durch Medienarbeit und humanit\u00e4re Hilfe verbreitet. Die Organisation konzentriert sich auf langfristige, strukturelle und geistliche Ver\u00e4nderungen im Iran. Pulse 2.0 sprach mit der Gesch\u00e4ftsf\u00fchrerin von Transform Iran, Lana Silk, um mehr zu erfahren.  <\/p>\n\n<h3 class=\"wp-block-heading\">Lana Silk&#8217;s Hintergrund und F\u00fchrungsqualit\u00e4ten<\/h3>\n\n<p class=\"wp-block-paragraph\">K\u00f6nnen Sie mir mehr \u00fcber Ihren Hintergrund erz\u00e4hlen? sagte Silk:<\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Ich bin im Iran geboren und aufgewachsen, genau auf dem H\u00f6hepunkt der Revolution, die das heutige Regime des Landes, die Islamische Republik Iran, hervorbrachte. Meine Familie wanderte kurz vor meinem zehnten Geburtstag nach England aus. Ich schloss meine Sekundar- und Hochschulausbildung in England ab und erwarb einen ausgezeichneten Abschluss in Computertechnik am Imperial College. Anschlie\u00dfend absolvierte ich ein Postgraduiertenstudium in Marketing-Kommunikationsstrategie und psychischer Gesundheit und Jugendschutz. Die n\u00e4chsten 20 Jahre arbeitete ich in den Bereichen Kommunikation und Markenentwicklung, bevor ich eine berufliche Pause einlegte, um meine drei Kinder gro\u00dfzuziehen. In dieser Zeit hielt ich meine F\u00e4higkeiten durch Beratung auf dem Laufenden, insbesondere bei Start-ups und gemeinn\u00fctzigen Organisationen. Danach habe ich einige Jahre als Hochschulseelsorgerin gearbeitet, bevor ich mit meiner Familie in die USA zog, wo ich die Rolle des CEO f\u00fcr das US-B\u00fcro von Transform Iran \u00fcbernahm.&#8221;<\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Diese Reise bereitete mich darauf vor, die <em>globale Strategie von Transform Iran<\/em> zu leiten und auch <em>Kairos, unsere innovative KI-Plattform, auf<\/em>den Weg zu bringen <em>&#8211; so konnte<\/em>ich meine Erfahrungen in den Bereichen Technologie, Kommunikation und Arbeit zusammenf\u00fchren.&#8221;<\/p>\n\n<h3 class=\"wp-block-heading\">Wie Transform Iran gegr\u00fcndet wurde und was seine Aufgabe im Iran ist<\/h3>\n\n<p class=\"wp-block-paragraph\">  Wie ist die Idee f\u00fcr das Unternehmen entstanden? Silk hat sie geteilt: <\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Transform Iran wurde aus der Not heraus geboren. Im Iran ist es illegal, zum Christentum zu konvertieren oder christliche Ressourcen herzustellen, zu verbreiten oder zug\u00e4nglich zu machen. Wer mit einer Bibel oder christlicher Literatur erwischt wird, dem droht eine harte Strafe. Meine Eltern gr\u00fcndeten die Organisation, um dieses Bed\u00fcrfnis zu befriedigen, indem sie den Iranern Zugang zu christlicher Lehre, Gottesdienst und Gemeinschaft verschafften, und zwar auf eine Art und Weise, die die Regierung nicht unterbinden konnte.&#8221;<\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Von Anfang an haben wir die Technologie als Schl\u00fcssel f\u00fcr den Zugang genutzt. Wir leisteten Pionierarbeit bei der Ausstrahlung von Satellitenfernsehen in persischer Sprache und expandierten dann in 24\/7-Radio, Websites, Social-Media-Kan\u00e4le und mobile Apps. Wir begannen auch, die Bibel in die vielen ethnischen Sprachen des Iran zu \u00fcbersetzen, die noch nie eine Schrift in ihrer Muttersprache hatten. Jede Initiative war eine Antwort auf eine Frage: Wie k\u00f6nnen wir die Iraner in einem Land, in dem Zensur die Norm ist, sicher mit Hoffnung und Wahrheit verbinden?&#8221;<\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Der Iran wird immer wieder als eines der repressivsten und zensiertesten L\u00e4nder der Welt eingestuft. Satellitenanlagen sind verboten, und der Zugriff auf nicht-staatliche Inhalte kann zu hohen Geld- oder sogar Gef\u00e4ngnisstrafen f\u00fchren. Doch mit 60% der Bev\u00f6lkerung unter 30 Jahren sind die Iraner jung, technisch versiert und begierig darauf, die Grenzen des Regimes zu \u00fcberwinden. Diese Entschlossenheit hat unseren Drang zur Innovation befl\u00fcgelt. Technologie ist der effektivste &#8211; und oft der einzige &#8211; Weg, um die staatliche Kontrolle zu umgehen, und erm\u00f6glicht es Millionen von Iranern, sich sicher mit der Au\u00dfenwelt zu verbinden.&#8221;    <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Genau hier kommt Kairos ins Spiel. Kairos ist unser christlicher KI-Assistent, der Iranern eine sichere, anonyme M\u00f6glichkeit bietet, tiefgreifende Fragen zum Glauben zu stellen und genaue, interaktive Antworten zu erhalten. Er erm\u00f6glicht es jemandem, der vielleicht Angst hat, beim Bibellesen oder beim Besuch einer Kirche erwischt zu werden, dennoch zu forschen, zu lernen und sogar Seelsorge zu finden &#8211; und das alles ganz privat. Neben Kairos bieten wir auch ein kostenloses, sicheres Hochgeschwindigkeits-VPN an, das es Iranern erm\u00f6glicht, die staatliche \u00dcberwachung zu umgehen und sicher auf globale Inhalte zuzugreifen. Diese digitalen Ressourcen sind ein wichtiger Teil unserer Strategie, die Zensur zu durchbrechen und gleichzeitig die Nutzer vor staatlicher \u00dcberwachung zu sch\u00fctzen.    <\/p>\n<\/blockquote>\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/kairoschat.ai\/\" target=\"_blank\" rel=\"noreferrer noopener\">Laden Sie die Kairos App noch heute herunter &#8211; sie ist in \u00fcber 250 Sprachen kostenlos!<\/a><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\">&#8220;Obwohl die Technologie im Mittelpunkt unserer Arbeit steht, geht es bei Transform Iran nicht nur um digitale Innovation. Wir setzen uns auch f\u00fcr die Freilassung christlicher Gefangener ein, bieten Trauma-Beratung an, helfen Gl\u00e4ubigen bei der Flucht, wenn sie in Gefahr sind, und liefern Hilfsg\u00fcter an Menschen in Not. Zusammen ist dies ein ganzheitlicher Ansatz: praktische Hilfe, geistliche Betreuung und bahnbrechende Technologie.&#8221;<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/transformiran.com\/de\/unsere-arbeit\/\">Lesen Sie mehr \u00fcber unsere umfangreiche Arbeit<\/a><\/p>\n\n<div class=\"wp-block-group has-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-white-color has-text-color has-link-color wp-elements-1\">Erhalten Sie vertrauensw\u00fcrdige Updates aus dem Iran<\/h2>\n\n\n\n<p class=\"has-white-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\">Erhalten Sie monatliche Updates. Bleiben Sie informiert. Beten Sie mit Klarheit.   Stehen Sie an der Seite der Menschen im Iran.<\/p>\n\n\n<script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform-theme gform-theme--foundation gform-theme--framework gform-theme--orbital' data-form-theme='orbital' data-form-index='0' id='gform_wrapper_1' ><style>#gform_wrapper_1[data-form-index=\"0\"].gform-theme,[data-parent-form=\"1_0\"]{--gf-color-primary: #204ce5;--gf-color-primary-rgb: 32, 76, 229;--gf-color-primary-contrast: #fff;--gf-color-primary-contrast-rgb: 255, 255, 255;--gf-color-primary-darker: #001AB3;--gf-color-primary-lighter: #527EFF;--gf-color-secondary: #fff;--gf-color-secondary-rgb: 255, 255, 255;--gf-color-secondary-contrast: #112337;--gf-color-secondary-contrast-rgb: 17, 35, 55;--gf-color-secondary-darker: #F5F5F5;--gf-color-secondary-lighter: #FFFFFF;--gf-color-out-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-out-ctrl-light-rgb: 17, 35, 55;--gf-color-out-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-out-ctrl-light-lighter: #F5F5F5;--gf-color-out-ctrl-dark: #585e6a;--gf-color-out-ctrl-dark-rgb: 88, 94, 106;--gf-color-out-ctrl-dark-darker: #112337;--gf-color-out-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-color-in-ctrl: #fff;--gf-color-in-ctrl-rgb: 255, 255, 255;--gf-color-in-ctrl-contrast: #112337;--gf-color-in-ctrl-contrast-rgb: 17, 35, 55;--gf-color-in-ctrl-darker: #F5F5F5;--gf-color-in-ctrl-lighter: #FFFFFF;--gf-color-in-ctrl-primary: #204ce5;--gf-color-in-ctrl-primary-rgb: 32, 76, 229;--gf-color-in-ctrl-primary-contrast: #fff;--gf-color-in-ctrl-primary-contrast-rgb: 255, 255, 255;--gf-color-in-ctrl-primary-darker: #001AB3;--gf-color-in-ctrl-primary-lighter: #527EFF;--gf-color-in-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-in-ctrl-light-rgb: 17, 35, 55;--gf-color-in-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-in-ctrl-light-lighter: #F5F5F5;--gf-color-in-ctrl-dark: #585e6a;--gf-color-in-ctrl-dark-rgb: 88, 94, 106;--gf-color-in-ctrl-dark-darker: #112337;--gf-color-in-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-radius: 3px;--gf-font-size-secondary: 14px;--gf-font-size-tertiary: 13px;--gf-icon-ctrl-number: url(\"data:image\/svg+xml,%3Csvg width='8' height='14' viewBox='0 0 8 14' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M4 0C4.26522 5.96046e-08 4.51957 0.105357 4.70711 0.292893L7.70711 3.29289C8.09763 3.68342 8.09763 4.31658 7.70711 4.70711C7.31658 5.09763 6.68342 5.09763 6.29289 4.70711L4 2.41421L1.70711 4.70711C1.31658 5.09763 0.683417 5.09763 0.292893 4.70711C-0.0976311 4.31658 -0.097631 3.68342 0.292893 3.29289L3.29289 0.292893C3.48043 0.105357 3.73478 0 4 0ZM0.292893 9.29289C0.683417 8.90237 1.31658 8.90237 1.70711 9.29289L4 11.5858L6.29289 9.29289C6.68342 8.90237 7.31658 8.90237 7.70711 9.29289C8.09763 9.68342 8.09763 10.3166 7.70711 10.7071L4.70711 13.7071C4.31658 14.0976 3.68342 14.0976 3.29289 13.7071L0.292893 10.7071C-0.0976311 10.3166 -0.0976311 9.68342 0.292893 9.29289Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-select: url(\"data:image\/svg+xml,%3Csvg width='10' height='6' viewBox='0 0 10 6' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M0.292893 0.292893C0.683417 -0.097631 1.31658 -0.097631 1.70711 0.292893L5 3.58579L8.29289 0.292893C8.68342 -0.0976311 9.31658 -0.0976311 9.70711 0.292893C10.0976 0.683417 10.0976 1.31658 9.70711 1.70711L5.70711 5.70711C5.31658 6.09763 4.68342 6.09763 4.29289 5.70711L0.292893 1.70711C-0.0976311 1.31658 -0.0976311 0.683418 0.292893 0.292893Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-search: url(\"data:image\/svg+xml,%3Csvg width='640' height='640' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath d='M256 128c-70.692 0-128 57.308-128 128 0 70.691 57.308 128 128 128 70.691 0 128-57.309 128-128 0-70.692-57.309-128-128-128zM64 256c0-106.039 85.961-192 192-192s192 85.961 192 192c0 41.466-13.146 79.863-35.498 111.248l154.125 154.125c12.496 12.496 12.496 32.758 0 45.254s-32.758 12.496-45.254 0L367.248 412.502C335.862 434.854 297.467 448 256 448c-106.039 0-192-85.962-192-192z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-label-space-y-secondary: var(--gf-label-space-y-md-secondary);--gf-ctrl-border-color: #686e77;--gf-ctrl-size: var(--gf-ctrl-size-md);--gf-ctrl-label-color-primary: #112337;--gf-ctrl-label-color-secondary: #112337;--gf-ctrl-choice-size: var(--gf-ctrl-choice-size-md);--gf-ctrl-checkbox-check-size: var(--gf-ctrl-checkbox-check-size-md);--gf-ctrl-radio-check-size: var(--gf-ctrl-radio-check-size-md);--gf-ctrl-btn-font-size: var(--gf-ctrl-btn-font-size-md);--gf-ctrl-btn-padding-x: var(--gf-ctrl-btn-padding-x-md);--gf-ctrl-btn-size: var(--gf-ctrl-btn-size-md);--gf-ctrl-btn-border-color-secondary: #686e77;--gf-ctrl-file-btn-bg-color-hover: #EBEBEB;--gf-field-img-choice-size: var(--gf-field-img-choice-size-md);--gf-field-img-choice-card-space: var(--gf-field-img-choice-card-space-md);--gf-field-img-choice-check-ind-size: var(--gf-field-img-choice-check-ind-size-md);--gf-field-img-choice-check-ind-icon-size: var(--gf-field-img-choice-check-ind-icon-size-md);--gf-field-pg-steps-number-color: rgba(17, 35, 55, 0.8);}<\/style><div id='gf_1' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_1' id='gform_1'  action='\/de\/wp-json\/wp\/v2\/posts\/36610#gf_1' data-formid='1' novalidate><div class='gf_invisible ginput_recaptchav3' data-sitekey='6LeOJgUrAAAAAPuuAflulrZo7spbjlHo45naz4Z3' data-tabindex='0'><input id=\"input_d6940e429b33b630150a5335bca4b629\" class=\"gfield_recaptcha_response\" type=\"hidden\" name=\"input_d6940e429b33b630150a5335bca4b629\" value=\"\"\/><\/div>\n                        <div class='gform-body gform_body'><div id='gform_fields_1' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_1_1\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-third field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_1'>First Name<\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_1_1' type='text' value='' class='large'    placeholder='First Name'  aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_1_5\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-third field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_5'>Last Name<\/label><div class='ginput_container ginput_container_text'><input name='input_5' id='input_1_5' type='text' value='' class='large'    placeholder='Last Name'  aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_1_4\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-third field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_4'>Email<\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_4' id='input_1_4' type='email' value='' class='large'   placeholder='Email'  aria-invalid=\"false\"  \/>\n                        <\/div><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_1' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Sign up'  \/> <input type='hidden' name='gform_ajax' value='form_id=1&amp;title=&amp;description=&amp;tabindex=0&amp;theme=orbital&amp;styles={&quot;inputPrimaryColor&quot;:&quot;#204ce5&quot;}&amp;hash=fc2cdfee64d0ed64edfd126c6336bc8e' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_1' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_1' id='gform_theme_1' value='orbital' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_1' id='gform_style_settings_1' value='{&quot;inputPrimaryColor&quot;:&quot;#204ce5&quot;}' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_1' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='1' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='ljonRPobi8verZjTiq72XWBhCds1Vy9oihiJwhzWCkj6b6ocM4wx5g2fSY1d0slobFUyKnMhMxScpA7txzmGWxZjO1XQMV6L6Ohjf8btpTUkkEk=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_1' value='WyJbXSIsIjYxZTg1MmUwMmZjNzkzZTQxZWUyZDJjMjJjMWJmZjJiIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_1' id='gform_target_page_number_1' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_1' id='gform_source_page_number_1' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_1' id='gform_ajax_frame_1' title='Dieser iframe enth\u00e4lt die erforderliche Logik um Gravity Forms Formulare mit AJAX zu handhaben.'><\/iframe>\n\t\t                <script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 1, 'https:\/\/transformiran.com\/app\/plugins\/gravityforms\/images\/spinner.svg', false );jQuery('#gform_ajax_frame_1').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_1');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_1').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_1').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_1').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_1').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_1').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_1').val();gformInitSpinner( 1, 'https:\/\/transformiran.com\/app\/plugins\/gravityforms\/images\/spinner.svg', false );jQuery(document).trigger('gform_page_loaded', [1, current_page]);window['gf_submitting_1'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_1').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_1').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [1]);window['gf_submitting_1'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_1').text());}else{jQuery('#gform_1').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"1\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_1\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_1\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_1\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 1, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n<\/div><\/div>\n\n<p class=\"wp-block-paragraph\">&#8220;Was meine Aufgaben betrifft, so leite ich derzeit unser B\u00fcro in den USA, setze und \u00fcberwache globale strategische Ziele, leite die Kommunikationsstrategie und verwalte die Beziehungen zu unseren Partnern. Au\u00dferdem \u00fcberwache ich die Budgets und stelle sicher, dass jedes Projekt mit unserer Kernaufgabe \u00fcbereinstimmt. Ab Januar 2026 werde ich die Rolle des internationalen Pr\u00e4sidenten \u00fcbernehmen. Mit gemeinn\u00fctzigen B\u00fcros in sechs L\u00e4ndern und Teams von Mitarbeitern und Freiwilligen in 19 L\u00e4ndern werde ich daf\u00fcr verantwortlich sein, dass unsere Mitarbeiter erfolgreich sind, unsere Systeme schlank und effektiv sind und unsere Ressourcen &#8211; sowohl personell als auch finanziell &#8211; maximiert werden, um eine nachhaltige Wirkung zu erzielen.&#8221;<\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Kurz gesagt, Transform Iran begann mit der Berufung, den Verfolgten zu dienen, und heute wird diese Berufung mit demselben Herzen fortgesetzt, jetzt ausgedr\u00fcckt durch verbesserte Innovation. Kairos ist der neueste Ausdruck dieser Berufung &#8211; eine Marke innerhalb von Transform Iran, die modernste KI-Technologie einsetzt, um das Unm\u00f6gliche f\u00fcr die Iraner m\u00f6glich zu machen.&#8221;<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/transformiran.com\/de\/unsere-arbeit\/entwicklung-von-fuhrungsqualitaten\/\">Lesen Sie mehr \u00fcber Kairos, unser KI-gest\u00fctztes J\u00fcngerschaftstool<\/a><\/p>\n\n<h3 class=\"wp-block-heading\">Lieblingserinnerung als Leiter von Transform Iran<\/h3>\n\n<p class=\"wp-block-paragraph\">Was war bisher Ihre sch\u00f6nste Erinnerung an die Arbeit in diesem Unternehmen? Seide reflektiert: <\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Die Zusammenarbeit mit meinen Eltern, die Transform Iran gegr\u00fcndet haben, war unglaublich bedeutsam. Ihre Vision legte den Grundstein und es war mir eine Ehre, sie zu erweitern. Die Gr\u00fcndung von Kairos unter derselben Vision ist besonders bedeutsam: Es ist sowohl eine biblische Fortsetzung ihrer Mission als auch ein mutiger Schritt in die Zukunft, um den sich entwickelnden Bed\u00fcrfnissen und F\u00e4higkeiten der Iraner von heute gerecht zu werden.&#8221;<\/p>\n\n<h3 class=\"wp-block-heading\">Kerndienste und Tools f\u00fcr den digitalen Dienst<\/h3>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Kairos - The Power of Christian AI in Mission\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/QjDEkAI8h4Y?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/kairoschat.ai\/\" target=\"_blank\" rel=\"noreferrer noopener\">Laden Sie die Kairos App noch heute herunter &#8211; sie ist in \u00fcber 250 Sprachen kostenlos!<\/a><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\">Was sind die wichtigsten Dienstleistungen des Unternehmens? erkl\u00e4rte Silk:<\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Transform Iran ist f\u00fcr die Iraner da, die unter einem der am st\u00e4rksten zensierten und unterdr\u00fcckerischen Regime der Welt leben. W\u00e4hrend wir geistliche, emotionale und praktische Unterst\u00fctzung durch Rundfunk, Bibel\u00fcbersetzung, F\u00fcrsprache, Beratung und Hilfe leisten, bleibt die Technologie eine der m\u00e4chtigsten M\u00f6glichkeiten, die Iraner sicher und effektiv zu erreichen. Daher umfassen unsere digitalen Ressourcen:  <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Kairos: unser Flaggschiff unter den KI-Assistenten<\/strong>, der in 256 Sprachen verf\u00fcgbar ist und auf sichere, anonyme und skalierbare Weise Fragen zum Glauben beantworten, Beratung anbieten und J\u00fcngerschaft vermitteln kann. F\u00fcr die Iraner ist Anonymit\u00e4t nicht nur eine Annehmlichkeit &#8211; sie ist lebensrettend <\/li>\n\n\n\n<li><strong>TI VPN: ein sicheres, kostenloses VPN<\/strong> zur Umgehung der Regierungsbeschr\u00e4nkungen und \u00dcberwachung im Iran<\/li>\n\n\n\n<li><strong>Broadcasting Network: <\/strong>Christliches <strong>24\/7-Satellitenfernsehen <\/strong>, drei Radiosender, Websites, soziale Medienkan\u00e4le und mobile Apps, die Millionen von Menschen erreichen<\/li>\n\n\n\n<li><strong>Persian Community Church<\/strong>: eine Online-Kirchengemeinde, die monatlich 20.000-25.000 Iraner mit Lehre und Gemeinschaft verbindet<\/li>\n\n\n\n<li><strong>Bibel\u00fcbersetzung<\/strong>: \u00dcbersetzung der Heiligen Schrift in die ethnischen Sprachen des Irans, die noch keinen Zugang haben<\/li>\n<\/ul>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Diejenigen, die eine tiefere Verbindung w\u00fcnschen, k\u00f6nnen Berater anrufen, die unsere Leitungen von au\u00dferhalb des Landes besetzen, und sich schlie\u00dflich, wenn Vertrauen und Sicherheit hergestellt sind, echten Kirchen anschlie\u00dfen, die sich in H\u00e4usern im ganzen Iran treffen.<\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\">Kurz gesagt, Kairos ist der neueste und innovativste Ausdruck der Mission von Transform Iran und verbindet modernste Technologie mit der zeitlosen Botschaft der Hoffnung.&#8221;<\/p>\n\n<h3 class=\"wp-block-heading\">Herausforderungen f\u00fcr den christlichen Dienst im Iran<\/h3>\n\n<p class=\"wp-block-paragraph\">Hatten Sie in letzter Zeit irgendwelche Herausforderungen in Ihrem Arbeitsbereich? Seide hat es best\u00e4tigt: <\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Die iranische Regierung versucht st\u00e4ndig, unsere Netzwerke zu infiltrieren, unsere Plattformen zu hacken und unsere Online-Pr\u00e4senz zu blockieren. <strong>Aber Innovation liegt in unserer DNA<\/strong>. So wie wir bei der Satelliten\u00fcbertragung Pionierarbeit geleistet haben, nutzen wir heute Tools wie Kairos, digitale Unterst\u00fctzungssysteme und sichere VPNs, um den Bedrohungen einen Schritt voraus zu sein und einen sicheren Zugang f\u00fcr die Iraner zu gew\u00e4hrleisten.&#8221; <\/p>\n\n<h3 class=\"wp-block-heading\">Entwicklung der Technologie des Unternehmens<\/h3>\n\n<p class=\"wp-block-paragraph\">Wie hat sich die Technologie des Unternehmens seit seiner Gr\u00fcndung entwickelt? Silk hat festgestellt: <\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Transform Iran war schon immer auf dem neuesten Stand der Technik. Wir waren die ersten, die vor mehr als 20 Jahren christliches Fernsehen in Farsi ausstrahlten, als dies noch niemand tat. Wir waren unter den Ersten, die Zoom f\u00fcr gro\u00df angelegte digitale Gemeindeversammlungen nutzten &#8211; lange vor der Pandemie &#8211; so sehr, dass unser Team in direktem Kontakt mit den Zoom-Ingenieuren stand, um Fehler zu beheben, weil ihr System noch nicht mit Hunderten von gleichzeitigen Nutzern umgehen konnte. Wir haben auch Pionierarbeit f\u00fcr interaktive Online-Gemeinden in Farsi geleistet, mehrere 24\/7-Radiosender gestartet und eine der ersten sicheren Online-Fragen- und Antworten-Plattformen f\u00fcr Iraner entwickelt, um Glaubensfragen zu erkunden.&#8221;<\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Jetzt betreten wir mit dem Start von Kairos wieder einmal Neuland &#8211; wir bieten seelsorgerische Unterst\u00fctzung, theologische Lehre und J\u00fcngerschaft unter der Zensur im Iran. Kairos erm\u00f6glicht es den Iranern, Fragen zu stellen und den Glauben auf eine sichere, skalierbare und anonyme Weise zu erforschen &#8211; etwas, das noch vor wenigen Jahren unvorstellbar war.&#8221;<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Jeder Schritt spiegelt das gleiche Prinzip wider: Nutzen Sie die Technologie, um den Menschen dort zu helfen, wo Regierungen und Zensoren versuchen, sie zum Schweigen zu bringen, und entwickeln Sie Werkzeuge, die sicherstellen, dass die Iraner trotz der Risiken mit der Wahrheit und der Hoffnung in Kontakt kommen k\u00f6nnen.<\/p>\n<\/blockquote>\n\n<h3 class=\"wp-block-heading\">Wichtige Meilensteine f\u00fcr das Wachstum von Transform Iran<\/h3>\n\n<p class=\"wp-block-paragraph\">  Was waren einige der wichtigsten Meilensteine des Unternehmens? Zitierte Seide: <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>2000<\/strong>: Pionierarbeit bei der Ausstrahlung christlicher Fernsehsendungen auf Farsi (die ersten Programme wurden 2001 unter dem Namen &#8216;Sama TV&#8217; ausgestrahlt)<\/li>\n\n\n\n<li class=\"has-black-color has-text-color has-link-color wp-elements-3\"><strong>2005<\/strong>: Beginn des Trauma-Beratungs- und Aufkl\u00e4rungsprojekts &#8216;Pearl of Persia&#8217;, das sich an Prostituierte und Drogenabh\u00e4ngige im Iran richtet<\/li>\n\n\n\n<li><strong>2007<\/strong>: Gr\u00fcndung des Farsi Christian News Network<a href=\"https:\/\/fcnn.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">(fcnn.com<\/a>), das den Iranern wichtige unzensierte Nachrichten bietet<\/li>\n\n\n\n<li><strong>2015<\/strong>: Einf\u00fchrung von &#8216;Porpasokh&#8217;, einer interaktiven Q&amp;A-Website, die Fragen zu Glaube und Spiritualit\u00e4t aus christlicher Sicht beantwortet (normalerweise im Iran illegal)<\/li>\n\n\n\n<li><strong>2018<\/strong>: Start der digitalen Kirche in Farsi: Persian Community Church (erste interaktive Online-Gemeinde in Farsi)<\/li>\n\n\n\n<li><strong>2020<\/strong>: Sama TV beginnt mit Live-\u00dcbertragungen am Freitagabend; jetzt k\u00f6nnen Zuschauer aus dem Iran anrufen und mit den Moderatoren interagieren<\/li>\n\n\n\n<li><strong>2021<\/strong>: Start des christlichen Radios auf Farsi (Persian World Radio)<\/li>\n\n\n\n<li><strong>2021<\/strong>: Beginn der \u00dcbersetzung der christlichen Bibel in die ethnischen Sprachen des Iran<\/li>\n\n\n\n<li><strong>2025<\/strong>: Start von Kairos (kostenlose christliche KI in 256 Sprachen) + kostenloses VPN f\u00fcr Iraner<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Gesamter adressierbarer Markt (TAM)<\/h3>\n\n<p class=\"wp-block-paragraph\">Welche Gr\u00f6\u00dfe hat der gesamte adressierbare Markt (TAM), den das Unternehmen anstrebt? Seide bewertet: <\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Der unmittelbare Fokus sind die 90 Millionen Iraner im Iran, gefolgt von den 5-6 Millionen Iranern in der iranischen Diaspora. Dann unsere afghanischen und tadschikischen Nachbarn, die eine sehr \u00e4hnliche Sprache sprechen und kulturell eng mit dem Iran verbunden sind.&#8221;<\/p>\n\n<h3 class=\"wp-block-heading\">Was Transform Iran von anderen Ministerien unterscheidet<\/h3>\n\n<p class=\"wp-block-paragraph\">Wodurch unterscheidet sich das Unternehmen von seiner Konkurrenz? Seide bejaht: <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Transform Iran ist das gr\u00f6\u00dfte christliche Netzwerk im Iran, mit Hunderten von Kirchen in 53 St\u00e4dten und einer Reichweite, die Millionen von Menschen hilft. \u00dcber dieses Netzwerk bieten wir sowohl geistlichen Beistand als auch praktische Hilfe &#8211; Nahrungsmittel, medizinische Versorgung und Nothilfe &#8211; in einem Umfang, den keine andere Organisation erreichen kann. Als OFAC-zertifizierte gemeinn\u00fctzige Organisation sind wir au\u00dferdem in der Lage, Ressourcen von au\u00dferhalb des Irans sicher in das Land zu leiten und sicherzustellen, dass sie sicher an die Bed\u00fcrftigen verteilt werden.  <\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\">&#8220;Au\u00dferhalb des Irans sind wir die am besten vernetzte Gemeinschaft iranischer Christen in der Diaspora, mit gemeinn\u00fctzigen B\u00fcros in sechs L\u00e4ndern und Teams in 19 L\u00e4ndern. Diese globale Reichweite erm\u00f6glicht es uns, strategische Projekte ins Leben zu rufen, die Iraner sowohl innerhalb als auch au\u00dferhalb des Landes unterst\u00fctzen.&#8221;<\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Was uns au\u00dferdem auszeichnet, ist unsere F\u00e4higkeit, praktische Hilfe, spirituelle Unterst\u00fctzung und modernste Technologie miteinander zu verbinden, jetzt durch Kairos, indem wir jahrzehntelange vertrauensvolle Arbeit mit der Skalierbarkeit und Anonymit\u00e4t von KI kombinieren und den Iranern sicheren Zugang zu seelsorgerischer Betreuung und Antworten auf ihre tiefsten Fragen geben, wie es keine andere Organisation kann.&#8221;<\/p>\n\n<h3 class=\"wp-block-heading\">Zuk\u00fcnftige Ziele f\u00fcr Transform Iran und die Transformation des Irans<\/h3>\n\n<p class=\"wp-block-paragraph\">Was sind einige der zuk\u00fcnftigen Ziele des Unternehmens? Seide unterstreicht: <\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Wir wollen einen freien und ver\u00e4nderten Iran, in dem jeder Mensch das Recht und die Freiheit hat, seinen Glauben zu w\u00e4hlen und ihn frei zu \u00e4u\u00dfern. Wir wollen, dass die soziale Gerechtigkeit im Iran wiederhergestellt wird und die verzweifelten Auswirkungen von Armut, Sucht, Missbrauch und Prostitution im Iran bek\u00e4mpft werden. Wir wollen auch dazu beitragen, dass das Land durch ein neues Regime geheilt wird, das nicht nur die Krise im Bereich der sozialen und psychischen Gesundheit angeht, sondern auch die Infrastruktur des Irans mit Wasser-, Gas- und Strommangel behebt und f\u00fcr alle Menschen zug\u00e4ngliche Wohnungen, Bildungs- und Berufsm\u00f6glichkeiten schafft.&#8221;<\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Die Technologie wird bei diesen Bem\u00fchungen weiterhin eine entscheidende Rolle spielen, unter anderem durch die Ausweitung von Kairos, die Verbesserung digitaler Gemeinschaften und die Vorbereitung von Systemen, die einen langfristigen positiven Wandel unterst\u00fctzen k\u00f6nnen, wenn sich das politische Klima \u00e4ndert.&#8221;<\/p>\n\n<h3 class=\"wp-block-heading\">Abschlie\u00dfende Gedanken zur Zukunft des Irans und seinen globalen Auswirkungen<\/h3>\n\n<p class=\"wp-block-paragraph\">Gibt es noch andere Themen, die Sie gerne besprechen m\u00f6chten? Seide schloss: <\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Der Iran steht an der Schwelle eines bedeutenden langfristigen Wandels. Es geht nicht mehr um ein &#8216;ob&#8217;, sondern um ein &#8216;wie&#8217; und &#8216;wann&#8217;. <em>Jetzt<\/em> ist es an der Zeit, sich vorzubereiten und Systeme, Prozesse, Produkte und Netzwerke einzurichten, die in der Lage sind, einen gesunden, stabilen und langfristigen Wandel im Iran zu unterst\u00fctzen.&#8221; <\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Und ein Wandel im Iran ist nicht nur gut f\u00fcr das iranische Volk. Er ist auch gut f\u00fcr den Rest der Welt. Stellen Sie sich vor, was es bedeuten w\u00fcrde, wenn die Kraft, die hinter den Stellvertretern des Irans und den vielen anderen \u00dcbelt\u00e4tern in der Welt steht, die der Iran finanziert, entwurzelt w\u00fcrde und aufh\u00f6rte zu operieren?&#8221;<\/p>\n\n<p class=\"wp-block-paragraph\">Helfen Sie uns, die Botschaft der Hoffnung, des Mutes und der St\u00e4rke zu den Menschen im Iran zu bringen, helfen Sie uns, ihre Stimmen zu verst\u00e4rken, und helfen Sie uns, uns gut vorzubereiten, damit wir, wenn der Wandel eintritt, nicht einen weiteren Fall einer gest\u00fcrzten Regierung erleben, der zu Chaos im Land f\u00fchrt.<\/p>\n\n<p class=\"wp-block-paragraph\"><em>Urspr\u00fcnglich ver\u00f6ffentlicht auf: <a href=\"https:\/\/pulse2.com\/transform-iran-profile-lana-silk-interview\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pulse 2.0<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erfahren Sie, wie Transform Iran Technologie und k\u00fcnstliche Intelligenz einsetzt, um den Glauben zu f\u00f6rdern. In diesem Pulse 2.0-Interview erz\u00e4hlt Lana, wie Innovation dabei hilft, Menschen in risikoreichen und eingeschr\u00e4nkten Umgebungen zu erreichen und zu J\u00fcngern zu machen. <\/p>\n","protected":false},"author":6,"featured_media":36604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"om_disable_all_campaigns":false,"_mi_skip_tracking":false,"footnotes":""},"categories":[123],"tags":[110,113,386,108],"class_list":["post-36610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsroom-de","tag-evangelisation","tag-juengerschaft","tag-kairos-ki","tag-regierung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tech-Interview mit Pulse 2.0: Glaubensbasierter Einsatz und Innovation - Transform Iran<\/title>\n<meta name=\"description\" content=\"Erfahren Sie, wie Transform Iran Technologie und k\u00fcnstliche Intelligenz einsetzt, um den Glauben zu f\u00f6rdern. In diesem Pulse 2.0-Interview erfahren Sie, wie Innovation dabei hilft, Menschen in risikoreichen und eingeschr\u00e4nkten Umgebungen zu erreichen und zu J\u00fcngern zu machen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tech-Interview mit Pulse 2.0: Glaubensbasierter Einsatz und Innovation - Transform Iran\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie, wie Transform Iran Technologie und k\u00fcnstliche Intelligenz einsetzt, um den Glauben zu f\u00f6rdern. In diesem Pulse 2.0-Interview erfahren Sie, wie Innovation dabei hilft, Menschen in risikoreichen und eingeschr\u00e4nkten Umgebungen zu erreichen und zu J\u00fcngern zu machen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/\" \/>\n<meta property=\"og:site_name\" content=\"Transform Iran\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/222MinistriesUSAInc\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-18T16:51:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-09T01:43:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transformiran.com\/app\/uploads\/2026\/03\/Images-for-website.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"555\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ashleigh Bedford\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@222minint\" \/>\n<meta name=\"twitter:site\" content=\"@222minint\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ashleigh Bedford\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/newsroom-de\\\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/newsroom-de\\\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\\\/\"},\"author\":{\"name\":\"Ashleigh Bedford\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/#\\\/schema\\\/person\\\/901d817bcb841b949dbba5fa2886bfe3\"},\"headline\":\"Tech-Interview mit Pulse 2.0: Glaubensbasierter Einsatz und Innovation\",\"datePublished\":\"2026-03-18T16:51:59+00:00\",\"dateModified\":\"2026-06-09T01:43:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/newsroom-de\\\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\\\/\"},\"wordCount\":2489,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/newsroom-de\\\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2026\\\/03\\\/Images-for-website.jpg\",\"keywords\":[\"Evangelisation\",\"J\u00fcngerschaft\",\"Kairos &amp; KI\",\"Regierung\"],\"articleSection\":[\"Newsroom\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transformiran.com\\\/de\\\/newsroom-de\\\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/newsroom-de\\\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\\\/\",\"url\":\"https:\\\/\\\/transformiran.com\\\/de\\\/newsroom-de\\\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\\\/\",\"name\":\"Tech-Interview mit Pulse 2.0: Glaubensbasierter Einsatz und Innovation - Transform Iran\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/newsroom-de\\\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/newsroom-de\\\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2026\\\/03\\\/Images-for-website.jpg\",\"datePublished\":\"2026-03-18T16:51:59+00:00\",\"dateModified\":\"2026-06-09T01:43:56+00:00\",\"description\":\"Erfahren Sie, wie Transform Iran Technologie und k\u00fcnstliche Intelligenz einsetzt, um den Glauben zu f\u00f6rdern. In diesem Pulse 2.0-Interview erfahren Sie, wie Innovation dabei hilft, Menschen in risikoreichen und eingeschr\u00e4nkten Umgebungen zu erreichen und zu J\u00fcngern zu machen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/newsroom-de\\\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transformiran.com\\\/de\\\/newsroom-de\\\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/newsroom-de\\\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2026\\\/03\\\/Images-for-website.jpg\",\"contentUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2026\\\/03\\\/Images-for-website.jpg\",\"width\":1920,\"height\":555},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/newsroom-de\\\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/transformiran.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tech-Interview mit Pulse 2.0: Glaubensbasierter Einsatz und Innovation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/transformiran.com\\\/de\\\/\",\"name\":\"Transform Iran\",\"description\":\"Bringing the love and power of Christ to Iran - and beyond\",\"publisher\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transformiran.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/#organization\",\"name\":\"Transform Iran\",\"url\":\"https:\\\/\\\/transformiran.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2022\\\/11\\\/logo_grey.jpg\",\"contentUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2022\\\/11\\\/logo_grey.jpg\",\"width\":528,\"height\":90,\"caption\":\"Transform Iran\"},\"image\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/222MinistriesUSAInc\",\"https:\\\/\\\/x.com\\\/222minint\",\"https:\\\/\\\/www.instagram.com\\\/222ministriesinternational\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/de\\\/#\\\/schema\\\/person\\\/901d817bcb841b949dbba5fa2886bfe3\",\"name\":\"Ashleigh Bedford\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g\",\"caption\":\"Ashleigh Bedford\"},\"url\":\"https:\\\/\\\/transformiran.com\\\/de\\\/author\\\/ashleigh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tech-Interview mit Pulse 2.0: Glaubensbasierter Einsatz und Innovation - Transform Iran","description":"Erfahren Sie, wie Transform Iran Technologie und k\u00fcnstliche Intelligenz einsetzt, um den Glauben zu f\u00f6rdern. In diesem Pulse 2.0-Interview erfahren Sie, wie Innovation dabei hilft, Menschen in risikoreichen und eingeschr\u00e4nkten Umgebungen zu erreichen und zu J\u00fcngern zu machen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/","og_locale":"de_DE","og_type":"article","og_title":"Tech-Interview mit Pulse 2.0: Glaubensbasierter Einsatz und Innovation - Transform Iran","og_description":"Erfahren Sie, wie Transform Iran Technologie und k\u00fcnstliche Intelligenz einsetzt, um den Glauben zu f\u00f6rdern. In diesem Pulse 2.0-Interview erfahren Sie, wie Innovation dabei hilft, Menschen in risikoreichen und eingeschr\u00e4nkten Umgebungen zu erreichen und zu J\u00fcngern zu machen.","og_url":"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/","og_site_name":"Transform Iran","article_publisher":"https:\/\/www.facebook.com\/222MinistriesUSAInc","article_published_time":"2026-03-18T16:51:59+00:00","article_modified_time":"2026-06-09T01:43:56+00:00","og_image":[{"width":1920,"height":555,"url":"https:\/\/transformiran.com\/app\/uploads\/2026\/03\/Images-for-website.jpg","type":"image\/jpeg"}],"author":"Ashleigh Bedford","twitter_card":"summary_large_image","twitter_creator":"@222minint","twitter_site":"@222minint","twitter_misc":{"Verfasst von":"Ashleigh Bedford","Gesch\u00e4tzte Lesezeit":"12 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/#article","isPartOf":{"@id":"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/"},"author":{"name":"Ashleigh Bedford","@id":"https:\/\/transformiran.com\/de\/#\/schema\/person\/901d817bcb841b949dbba5fa2886bfe3"},"headline":"Tech-Interview mit Pulse 2.0: Glaubensbasierter Einsatz und Innovation","datePublished":"2026-03-18T16:51:59+00:00","dateModified":"2026-06-09T01:43:56+00:00","mainEntityOfPage":{"@id":"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/"},"wordCount":2489,"commentCount":0,"publisher":{"@id":"https:\/\/transformiran.com\/de\/#organization"},"image":{"@id":"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/#primaryimage"},"thumbnailUrl":"https:\/\/transformiran.com\/app\/uploads\/2026\/03\/Images-for-website.jpg","keywords":["Evangelisation","J\u00fcngerschaft","Kairos &amp; KI","Regierung"],"articleSection":["Newsroom"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/","url":"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/","name":"Tech-Interview mit Pulse 2.0: Glaubensbasierter Einsatz und Innovation - Transform Iran","isPartOf":{"@id":"https:\/\/transformiran.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/#primaryimage"},"image":{"@id":"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/#primaryimage"},"thumbnailUrl":"https:\/\/transformiran.com\/app\/uploads\/2026\/03\/Images-for-website.jpg","datePublished":"2026-03-18T16:51:59+00:00","dateModified":"2026-06-09T01:43:56+00:00","description":"Erfahren Sie, wie Transform Iran Technologie und k\u00fcnstliche Intelligenz einsetzt, um den Glauben zu f\u00f6rdern. In diesem Pulse 2.0-Interview erfahren Sie, wie Innovation dabei hilft, Menschen in risikoreichen und eingeschr\u00e4nkten Umgebungen zu erreichen und zu J\u00fcngern zu machen.","breadcrumb":{"@id":"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/#primaryimage","url":"https:\/\/transformiran.com\/app\/uploads\/2026\/03\/Images-for-website.jpg","contentUrl":"https:\/\/transformiran.com\/app\/uploads\/2026\/03\/Images-for-website.jpg","width":1920,"height":555},{"@type":"BreadcrumbList","@id":"https:\/\/transformiran.com\/de\/newsroom-de\/tech-interview-mit-pulse-2-0-glaubensbasierter-einsatz-und-innovation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/transformiran.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Tech-Interview mit Pulse 2.0: Glaubensbasierter Einsatz und Innovation"}]},{"@type":"WebSite","@id":"https:\/\/transformiran.com\/de\/#website","url":"https:\/\/transformiran.com\/de\/","name":"Transform Iran","description":"Bringing the love and power of Christ to Iran - and beyond","publisher":{"@id":"https:\/\/transformiran.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transformiran.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/transformiran.com\/de\/#organization","name":"Transform Iran","url":"https:\/\/transformiran.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/transformiran.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/transformiran.com\/app\/uploads\/2022\/11\/logo_grey.jpg","contentUrl":"https:\/\/transformiran.com\/app\/uploads\/2022\/11\/logo_grey.jpg","width":528,"height":90,"caption":"Transform Iran"},"image":{"@id":"https:\/\/transformiran.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/222MinistriesUSAInc","https:\/\/x.com\/222minint","https:\/\/www.instagram.com\/222ministriesinternational\/"]},{"@type":"Person","@id":"https:\/\/transformiran.com\/de\/#\/schema\/person\/901d817bcb841b949dbba5fa2886bfe3","name":"Ashleigh Bedford","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g","caption":"Ashleigh Bedford"},"url":"https:\/\/transformiran.com\/de\/author\/ashleigh\/"}]}},"_links":{"self":[{"href":"https:\/\/transformiran.com\/de\/wp-json\/wp\/v2\/posts\/36610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transformiran.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transformiran.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transformiran.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/transformiran.com\/de\/wp-json\/wp\/v2\/comments?post=36610"}],"version-history":[{"count":5,"href":"https:\/\/transformiran.com\/de\/wp-json\/wp\/v2\/posts\/36610\/revisions"}],"predecessor-version":[{"id":38798,"href":"https:\/\/transformiran.com\/de\/wp-json\/wp\/v2\/posts\/36610\/revisions\/38798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transformiran.com\/de\/wp-json\/wp\/v2\/media\/36604"}],"wp:attachment":[{"href":"https:\/\/transformiran.com\/de\/wp-json\/wp\/v2\/media?parent=36610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transformiran.com\/de\/wp-json\/wp\/v2\/categories?post=36610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transformiran.com\/de\/wp-json\/wp\/v2\/tags?post=36610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}