{"id":33294,"date":"2025-10-07T15:02:58","date_gmt":"2025-10-07T14:02:58","guid":{"rendered":"https:\/\/transformiran.com\/sin-categorizar\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/"},"modified":"2025-10-08T15:05:03","modified_gmt":"2025-10-08T14:05:03","slug":"jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones","status":"publish","type":"post","link":"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/","title":{"rendered":"Jes\u00fas en casa y el Islam fuera: la doble vida de los ni\u00f1os cristianos en Ir\u00e1n: Noticias de la Red de Misiones"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por Joanne Khmel<\/p>\n\n<p class=\"wp-block-paragraph\">Ir\u00e1n (MNN) &#8211; Para un ni\u00f1o cristiano que crece en Ir\u00e1n, la clave es comprender la Verdad.<\/p>\n\n<p class=\"wp-block-paragraph\">En la escuela, los ni\u00f1os cristianos deben vivir una doble vida. El hogar es el \u00fanico lugar seguro para explorar la verdad real, mientras que fuera domina la ideolog\u00eda isl\u00e1mica. <\/p>\n\n<p class=\"wp-block-paragraph\">Lana Silk de <a href=\"https:\/\/www.mnnonline.org\/mission_groups\/transform-iran\/\" target=\"_blank\" rel=\"noreferrer noopener\">\n  <strong>Transform Iran<\/strong>\n<\/a> dice: &#8220;Todo el material tiene un sabor isl\u00e1mico. Incluso las matem\u00e1ticas o las artes&#8221;.<\/p>\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de las asignaturas normales, los alumnos reciben clases de religi\u00f3n para aprender el islam y el \u00e1rabe, de modo que puedan recitar Namaz y convertirse en aut\u00e9nticos musulmanes. Incluso las historias conocidas de la Biblia se reescriben a trav\u00e9s de una lente isl\u00e1mica. <\/p>\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:44% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/transformiran.com\/app\/uploads\/2025\/10\/Sama_Kindergarten_and_Elementary_School_-_First_day_of_Iranian_new_education_year_-_for_Kindergarten_students_and_elementary_school_newcomers_-_Qods_zonetown_-_city_of_Nishapur_057.jpg\" alt=\"\" class=\"wp-image-33275 size-full\" srcset=\"https:\/\/transformiran.com\/app\/uploads\/2025\/10\/Sama_Kindergarten_and_Elementary_School_-_First_day_of_Iranian_new_education_year_-_for_Kindergarten_students_and_elementary_school_newcomers_-_Qods_zonetown_-_city_of_Nishapur_057.jpg 640w, https:\/\/transformiran.com\/app\/uploads\/2025\/10\/Sama_Kindergarten_and_Elementary_School_-_First_day_of_Iranian_new_education_year_-_for_Kindergarten_students_and_elementary_school_newcomers_-_Qods_zonetown_-_city_of_Nishapur_057-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size wp-block-paragraph\">&#8220;Tienen que ser capaces de hablar de la versi\u00f3n isl\u00e1mica en la escuela, seguir el juego y fingir que esa es su realidad, todo ello manteniendo las diferencias claras en sus mentes y sin mezclarlas. Es mucha presi\u00f3n para los ni\u00f1os&#8221;, explica Silk.<\/p>\n<\/div><\/div>\n\n<p class=\"has-small-font-size wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">En casa, los padres cristianos intentan mantener a sus hijos cimentados en las Escrituras, pero a muchos les falta formaci\u00f3n. Ah\u00ed es donde interviene Transform Iran. <\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Hacemos mucho ministerio centrado en los ni\u00f1os y hemos creado recursos enfocados a los ni\u00f1os para dar a los padres las herramientas que necesitan para ayudar a inculcar estos fundamentos a sus hijos a una edad temprana, para que crezcan conociendo la verdad&#8221;, dice Silk.<\/p>\n\n<p class=\"wp-block-paragraph\">Siempre que es posible, el ministerio organiza reuniones discretas -cada pocas semanas o mensualmente- en peque\u00f1os grupos en casa dirigidos por profesores formados que utilizan materiales b\u00edblicos apropiados para cada edad.<\/p>\n\n<p class=\"wp-block-paragraph\">Para muchos ni\u00f1os, la diferencia entre verdad y mentira es tangible.<\/p>\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 44%\"><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size wp-block-paragraph\">&#8220;Experimentan el amor de Dios muy pronto en sus vidas en hogares cristianos y, sobre todo en el clima t\u00f3xico de Ir\u00e1n, reconocen que en casa hay alegr\u00eda y paz, algo que falta fuera de su hogar&#8221;, dice Silk.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/transformiran.com\/app\/uploads\/2025\/10\/Sama_Kindergarten_and_Elementary_School_-_First_day_of_Iranian_new_education_year_-_for_Kindergarten_students_and_elementary_school_newcomers_-_Qods_zonetown_-_city_of_Nishapur_064.jpg\" alt=\"\" class=\"wp-image-33282 size-full\" srcset=\"https:\/\/transformiran.com\/app\/uploads\/2025\/10\/Sama_Kindergarten_and_Elementary_School_-_First_day_of_Iranian_new_education_year_-_for_Kindergarten_students_and_elementary_school_newcomers_-_Qods_zonetown_-_city_of_Nishapur_064.jpg 640w, https:\/\/transformiran.com\/app\/uploads\/2025\/10\/Sama_Kindergarten_and_Elementary_School_-_First_day_of_Iranian_new_education_year_-_for_Kindergarten_students_and_elementary_school_newcomers_-_Qods_zonetown_-_city_of_Nishapur_064-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/div>\n\n<p class=\"has-small-font-size wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Sin embargo, esta doble vida pasa factura. Muchos ni\u00f1os luchan contra la ansiedad, la depresi\u00f3n y la baja autoestima mientras navegan por dos mundos en conflicto. Necesitan tus oraciones.  <\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Reza para que los padres iran\u00edes gu\u00eden sabiamente a sus hijos a trav\u00e9s de la tensi\u00f3n emocional de su entorno. Reza para que los ni\u00f1os se aferren a la verdad que conocen en casa. <\/p>\n\n<p class=\"wp-block-paragraph\">Obt\u00e9n m\u00e1s informaci\u00f3n sobre c\u00f3mo Transform Iran equipa a familias y ni\u00f1os para vivir fielmente en uno de los entornos m\u00e1s dif\u00edciles del mundo.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/transformiran.com\/es\/nuestro-trabajo\/llegar-a-los-ninos\/\">M\u00e1s informaci\u00f3n sobre c\u00f3mo Transform Iran est\u00e1 llegando a los ni\u00f1os de Ir\u00e1n<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><em>Foto del encabezado cortes\u00eda de Mohammad Moslehi v\u00eda Unsplash.<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><em>Fotos del recuadro: Escuela Infantil y Primaria Sama y Primer d\u00eda del nuevo curso educativo iran\u00ed (ambas fotos cortes\u00eda de Sonia Sevilla v\u00eda Wikimedia Commons).<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><em>Publicado originalmente en: <a href=\"https:\/\/www.mnnonline.org\/news\/jesus-at-home-and-islam-outside-the-double-life-of-christian-children-in-iran\/\">Mission Network News<\/a><\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Ir\u00e1n, los ni\u00f1os cristianos viven una doble vida. Obligados a recitar oraciones isl\u00e1micas y a ocultar su fe, la tensi\u00f3n les pasa factura. Descubre c\u00f3mo Transform Iran prepara a las familias para cimentar a sus hijos en la verdad b\u00edblica en medio de la creciente persecuci\u00f3n.  <\/p>\n","protected":false},"author":6,"featured_media":33273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"om_disable_all_campaigns":false,"_mi_skip_tracking":false,"footnotes":""},"categories":[161],"tags":[151,165,168,166],"class_list":["post-33294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-redaccion","tag-discipulado","tag-gobierno","tag-iglesia","tag-ninos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jes\u00fas en casa y el Islam fuera: la doble vida de los ni\u00f1os cristianos en Ir\u00e1n: Noticias de la Red de Misiones - Transform Iran<\/title>\n<meta name=\"description\" content=\"En Ir\u00e1n, los ni\u00f1os cristianos viven una doble vida. Obligados a recitar oraciones isl\u00e1micas y a ocultar su fe, la tensi\u00f3n les pasa factura. Descubre c\u00f3mo Transform Iran prepara a las familias para cimentar a sus hijos en la verdad b\u00edblica en medio de la creciente persecuci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jes\u00fas en casa y el Islam fuera: la doble vida de los ni\u00f1os cristianos en Ir\u00e1n: Noticias de la Red de Misiones - Transform Iran\" \/>\n<meta property=\"og:description\" content=\"En Ir\u00e1n, los ni\u00f1os cristianos viven una doble vida. Obligados a recitar oraciones isl\u00e1micas y a ocultar su fe, la tensi\u00f3n les pasa factura. Descubre c\u00f3mo Transform Iran prepara a las familias para cimentar a sus hijos en la verdad b\u00edblica en medio de la creciente persecuci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/\" \/>\n<meta property=\"og:site_name\" content=\"Transform Iran\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/222MinistriesUSAInc\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-07T14:02:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T14:05:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transformiran.com\/app\/uploads\/2025\/10\/mohammad-moslehi-5GWYLvnVJJg-unsplash-2048x1153-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1153\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ashleigh Bedford\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@222minint\" \/>\n<meta name=\"twitter:site\" content=\"@222minint\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ashleigh Bedford\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/redaccion\\\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/redaccion\\\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\\\/\"},\"author\":{\"name\":\"Ashleigh Bedford\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/#\\\/schema\\\/person\\\/901d817bcb841b949dbba5fa2886bfe3\"},\"headline\":\"Jes\u00fas en casa y el Islam fuera: la doble vida de los ni\u00f1os cristianos en Ir\u00e1n: Noticias de la Red de Misiones\",\"datePublished\":\"2025-10-07T14:02:58+00:00\",\"dateModified\":\"2025-10-08T14:05:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/redaccion\\\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\\\/\"},\"wordCount\":523,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/redaccion\\\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2025\\\/10\\\/mohammad-moslehi-5GWYLvnVJJg-unsplash-2048x1153-1.jpg\",\"keywords\":[\"Discipulado\",\"Gobierno\",\"Iglesia\",\"Ni\u00f1os\"],\"articleSection\":[\"Redacci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transformiran.com\\\/es\\\/redaccion\\\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/redaccion\\\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\\\/\",\"url\":\"https:\\\/\\\/transformiran.com\\\/es\\\/redaccion\\\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\\\/\",\"name\":\"Jes\u00fas en casa y el Islam fuera: la doble vida de los ni\u00f1os cristianos en Ir\u00e1n: Noticias de la Red de Misiones - Transform Iran\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/redaccion\\\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/redaccion\\\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2025\\\/10\\\/mohammad-moslehi-5GWYLvnVJJg-unsplash-2048x1153-1.jpg\",\"datePublished\":\"2025-10-07T14:02:58+00:00\",\"dateModified\":\"2025-10-08T14:05:03+00:00\",\"description\":\"En Ir\u00e1n, los ni\u00f1os cristianos viven una doble vida. Obligados a recitar oraciones isl\u00e1micas y a ocultar su fe, la tensi\u00f3n les pasa factura. Descubre c\u00f3mo Transform Iran prepara a las familias para cimentar a sus hijos en la verdad b\u00edblica en medio de la creciente persecuci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/redaccion\\\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transformiran.com\\\/es\\\/redaccion\\\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/redaccion\\\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2025\\\/10\\\/mohammad-moslehi-5GWYLvnVJJg-unsplash-2048x1153-1.jpg\",\"contentUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2025\\\/10\\\/mohammad-moslehi-5GWYLvnVJJg-unsplash-2048x1153-1.jpg\",\"width\":2048,\"height\":1153,\"caption\":\"The double life of Christian children in Iran\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/redaccion\\\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/transformiran.com\\\/es\\\/inicio-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jes\u00fas en casa y el Islam fuera: la doble vida de los ni\u00f1os cristianos en Ir\u00e1n: Noticias de la Red de Misiones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/transformiran.com\\\/es\\\/\",\"name\":\"Transform Iran\",\"description\":\"Bringing the love and power of Christ to Iran - and beyond\",\"publisher\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transformiran.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/#organization\",\"name\":\"Transform Iran\",\"url\":\"https:\\\/\\\/transformiran.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2022\\\/11\\\/logo_grey.jpg\",\"contentUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2022\\\/11\\\/logo_grey.jpg\",\"width\":528,\"height\":90,\"caption\":\"Transform Iran\"},\"image\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/222MinistriesUSAInc\",\"https:\\\/\\\/x.com\\\/222minint\",\"https:\\\/\\\/www.instagram.com\\\/222ministriesinternational\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/es\\\/#\\\/schema\\\/person\\\/901d817bcb841b949dbba5fa2886bfe3\",\"name\":\"Ashleigh Bedford\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g\",\"caption\":\"Ashleigh Bedford\"},\"url\":\"https:\\\/\\\/transformiran.com\\\/es\\\/author\\\/ashleigh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jes\u00fas en casa y el Islam fuera: la doble vida de los ni\u00f1os cristianos en Ir\u00e1n: Noticias de la Red de Misiones - Transform Iran","description":"En Ir\u00e1n, los ni\u00f1os cristianos viven una doble vida. Obligados a recitar oraciones isl\u00e1micas y a ocultar su fe, la tensi\u00f3n les pasa factura. Descubre c\u00f3mo Transform Iran prepara a las familias para cimentar a sus hijos en la verdad b\u00edblica en medio de la creciente persecuci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/","og_locale":"es_ES","og_type":"article","og_title":"Jes\u00fas en casa y el Islam fuera: la doble vida de los ni\u00f1os cristianos en Ir\u00e1n: Noticias de la Red de Misiones - Transform Iran","og_description":"En Ir\u00e1n, los ni\u00f1os cristianos viven una doble vida. Obligados a recitar oraciones isl\u00e1micas y a ocultar su fe, la tensi\u00f3n les pasa factura. Descubre c\u00f3mo Transform Iran prepara a las familias para cimentar a sus hijos en la verdad b\u00edblica en medio de la creciente persecuci\u00f3n.","og_url":"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/","og_site_name":"Transform Iran","article_publisher":"https:\/\/www.facebook.com\/222MinistriesUSAInc","article_published_time":"2025-10-07T14:02:58+00:00","article_modified_time":"2025-10-08T14:05:03+00:00","og_image":[{"width":2048,"height":1153,"url":"https:\/\/transformiran.com\/app\/uploads\/2025\/10\/mohammad-moslehi-5GWYLvnVJJg-unsplash-2048x1153-1.jpg","type":"image\/jpeg"}],"author":"Ashleigh Bedford","twitter_card":"summary_large_image","twitter_creator":"@222minint","twitter_site":"@222minint","twitter_misc":{"Escrito por":"Ashleigh Bedford","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/#article","isPartOf":{"@id":"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/"},"author":{"name":"Ashleigh Bedford","@id":"https:\/\/transformiran.com\/es\/#\/schema\/person\/901d817bcb841b949dbba5fa2886bfe3"},"headline":"Jes\u00fas en casa y el Islam fuera: la doble vida de los ni\u00f1os cristianos en Ir\u00e1n: Noticias de la Red de Misiones","datePublished":"2025-10-07T14:02:58+00:00","dateModified":"2025-10-08T14:05:03+00:00","mainEntityOfPage":{"@id":"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/"},"wordCount":523,"commentCount":0,"publisher":{"@id":"https:\/\/transformiran.com\/es\/#organization"},"image":{"@id":"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/#primaryimage"},"thumbnailUrl":"https:\/\/transformiran.com\/app\/uploads\/2025\/10\/mohammad-moslehi-5GWYLvnVJJg-unsplash-2048x1153-1.jpg","keywords":["Discipulado","Gobierno","Iglesia","Ni\u00f1os"],"articleSection":["Redacci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/","url":"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/","name":"Jes\u00fas en casa y el Islam fuera: la doble vida de los ni\u00f1os cristianos en Ir\u00e1n: Noticias de la Red de Misiones - Transform Iran","isPartOf":{"@id":"https:\/\/transformiran.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/#primaryimage"},"image":{"@id":"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/#primaryimage"},"thumbnailUrl":"https:\/\/transformiran.com\/app\/uploads\/2025\/10\/mohammad-moslehi-5GWYLvnVJJg-unsplash-2048x1153-1.jpg","datePublished":"2025-10-07T14:02:58+00:00","dateModified":"2025-10-08T14:05:03+00:00","description":"En Ir\u00e1n, los ni\u00f1os cristianos viven una doble vida. Obligados a recitar oraciones isl\u00e1micas y a ocultar su fe, la tensi\u00f3n les pasa factura. Descubre c\u00f3mo Transform Iran prepara a las familias para cimentar a sus hijos en la verdad b\u00edblica en medio de la creciente persecuci\u00f3n.","breadcrumb":{"@id":"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/#primaryimage","url":"https:\/\/transformiran.com\/app\/uploads\/2025\/10\/mohammad-moslehi-5GWYLvnVJJg-unsplash-2048x1153-1.jpg","contentUrl":"https:\/\/transformiran.com\/app\/uploads\/2025\/10\/mohammad-moslehi-5GWYLvnVJJg-unsplash-2048x1153-1.jpg","width":2048,"height":1153,"caption":"The double life of Christian children in Iran"},{"@type":"BreadcrumbList","@id":"https:\/\/transformiran.com\/es\/redaccion\/jesus-en-casa-y-el-islam-fuera-la-doble-vida-de-los-ninos-cristianos-en-iran-noticias-de-la-red-de-misiones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/transformiran.com\/es\/inicio-2\/"},{"@type":"ListItem","position":2,"name":"Jes\u00fas en casa y el Islam fuera: la doble vida de los ni\u00f1os cristianos en Ir\u00e1n: Noticias de la Red de Misiones"}]},{"@type":"WebSite","@id":"https:\/\/transformiran.com\/es\/#website","url":"https:\/\/transformiran.com\/es\/","name":"Transform Iran","description":"Bringing the love and power of Christ to Iran - and beyond","publisher":{"@id":"https:\/\/transformiran.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transformiran.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/transformiran.com\/es\/#organization","name":"Transform Iran","url":"https:\/\/transformiran.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transformiran.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/transformiran.com\/app\/uploads\/2022\/11\/logo_grey.jpg","contentUrl":"https:\/\/transformiran.com\/app\/uploads\/2022\/11\/logo_grey.jpg","width":528,"height":90,"caption":"Transform Iran"},"image":{"@id":"https:\/\/transformiran.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/222MinistriesUSAInc","https:\/\/x.com\/222minint","https:\/\/www.instagram.com\/222ministriesinternational\/"]},{"@type":"Person","@id":"https:\/\/transformiran.com\/es\/#\/schema\/person\/901d817bcb841b949dbba5fa2886bfe3","name":"Ashleigh Bedford","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g","caption":"Ashleigh Bedford"},"url":"https:\/\/transformiran.com\/es\/author\/ashleigh\/"}]}},"_links":{"self":[{"href":"https:\/\/transformiran.com\/es\/wp-json\/wp\/v2\/posts\/33294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transformiran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transformiran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transformiran.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/transformiran.com\/es\/wp-json\/wp\/v2\/comments?post=33294"}],"version-history":[{"count":1,"href":"https:\/\/transformiran.com\/es\/wp-json\/wp\/v2\/posts\/33294\/revisions"}],"predecessor-version":[{"id":33295,"href":"https:\/\/transformiran.com\/es\/wp-json\/wp\/v2\/posts\/33294\/revisions\/33295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transformiran.com\/es\/wp-json\/wp\/v2\/media\/33273"}],"wp:attachment":[{"href":"https:\/\/transformiran.com\/es\/wp-json\/wp\/v2\/media?parent=33294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transformiran.com\/es\/wp-json\/wp\/v2\/categories?post=33294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transformiran.com\/es\/wp-json\/wp\/v2\/tags?post=33294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}