{"id":26816,"date":"2024-11-08T15:53:56","date_gmt":"2024-11-08T15:53:56","guid":{"rendered":"https:\/\/transformiran.com\/non-classifiee\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/"},"modified":"2025-04-08T15:56:32","modified_gmt":"2025-04-08T14:56:32","slug":"les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui","status":"publish","type":"post","link":"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/","title":{"rendered":"Les d\u00e9fis auxquels sont confront\u00e9s les enfants iraniens aujourd&#8217;hui"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les Iraniens sont confront\u00e9s \u00e0 des d\u00e9fis difficiles : un gouvernement oppressif, une inflation croissante, une crise nationale de la sant\u00e9 mentale, une escalade des guerres et des conflits r\u00e9gionaux. Au milieu de ces difficult\u00e9s, de nombreux Iraniens trouvent l&#8217;espoir dans le message de J\u00e9sus-Christ &#8211; mais le d\u00e9fi de vivre cet espoir dans un pays musulman est grand, en particulier pour les enfants qui continuent d&#8217;\u00eatre endoctrin\u00e9s <a> <\/a>par l&#8217;islam \u00e0 l&#8217;\u00e9cole.<\/p>\n\n<p class=\"wp-block-paragraph\">Ceux qui ont d\u00fb s&#8217;enfuir continuent d&#8217;\u00eatre confront\u00e9s \u00e0 la pers\u00e9cution et aux difficult\u00e9s, mais cette fois en tant que r\u00e9fugi\u00e9s.<\/p>\n\n<h2 class=\"wp-block-heading\">Combien y a-t-il d&#8217;enfants iraniens ?<\/h2>\n\n<p class=\"wp-block-paragraph\">Il n&#8217;existe pas de statistiques pr\u00e9cises sur le nombre d&#8217;enfants en Iran. En tenant compte de toutes les sources disponibles, nos meilleures estimations indiquent qu&#8217;il y a quelque 8 \u00e0 10 millions d&#8217;enfants \u00e2g\u00e9s de 5 \u00e0 12 ans en Iran.  <\/p>\n\n<p class=\"wp-block-paragraph\">Il est \u00e9galement difficile d&#8217;obtenir des chiffres actualis\u00e9s concernant les r\u00e9fugi\u00e9s iraniens dans un pays donn\u00e9 ; il est encore plus difficile de d\u00e9terminer le nombre d&#8217;enfants. Les chiffres totalisent normalement tous les Iraniens dans chaque pays, mais cela inclut les Iraniens qui ont \u00e9migr\u00e9 &#8211; en tant que r\u00e9sidents officiels, leur qualit\u00e9 de vie est nettement meilleure que celle des r\u00e9fugi\u00e9s. Selon Macrotrends, il y avait plus de 3,7 millions de r\u00e9fugi\u00e9s iraniens en 2022, soit une augmentation de 9,91 % par rapport \u00e0 2021.  <\/p>\n\n<h2 class=\"wp-block-heading\">Pressions sur l&#8217;enfance en Iran<\/h2>\n\n<p class=\"has-blue-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\">Les enfants d&#8217;Iran sont confront\u00e9s \u00e0 des d\u00e9fis sans pr\u00e9c\u00e9dent.  <\/p>\n\n<p class=\"has-blue-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\">En plus de subir des r\u00e9gimes <strong>oppressifs<\/strong>, une propagande omnipr\u00e9sente, une <strong>pauvret\u00e9<\/strong> <strong>croissante<\/strong> et les effets d\u00e9vastateurs de la guerre et du <strong>d\u00e9sespoir<\/strong>, l&#8217;Iran est confront\u00e9 \u00e0 une crise de sant\u00e9 mentale de plus en plus grave. Par cons\u00e9quent, la majorit\u00e9 des enfants &#8211; en particulier ceux qui vivent dans des foyers sans l&#8217;espoir de J\u00e9sus-Christ &#8211; sont susceptibles d&#8217;avoir au moins un adulte dans leur vie qui lutte contre la <strong>d\u00e9pression<\/strong>, l&#8217;<strong>anxi\u00e9t\u00e9<\/strong> ou la <strong>toxicomanie<\/strong>. Le risque que cet enfant subisse un traumatisme du fait de sa vie familiale est grand.<\/p>\n\n<p class=\"has-blue-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\">En outre, le grand nombre de <strong>&#8220;sighe&#8221; (mariages temporaires <\/strong>) signifie qu&#8217;un nombre incalculable d&#8217;enfants (probablement des millions) naissent d&#8217;une seconde \u00e9pouse ou d&#8217;une \u00e9pouse temporaire, ce qui compromet leur avenir si le p\u00e8re d\u00e9cide de les abandonner ou d&#8217;abandonner leur m\u00e8re. Ce chiffre ne tient pas compte des enfants n\u00e9s de prostitu\u00e9es. On estime \u00e0 1 million le nombre de prostitu\u00e9es en Iran aujourd&#8217;hui (probablement plus). En Iran, la <strong>prostitution<\/strong> commence d\u00e8s l&#8217;\u00e2ge de 12 ans.<\/p>\n\n<p class=\"has-blue-color has-text-color has-link-color wp-elements-4 wp-block-paragraph\">Ces tendances, associ\u00e9es \u00e0 la pression de la pauvret\u00e9, ont conduit \u00e0 une estimation de 100 000 <strong>enfants des rues<\/strong> et de plus de 700 000 <strong>enfants qui travaillent<\/strong> en Iran.<\/p>\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-5 wp-block-paragraph\"><strong>Nous devons agir de toute urgence pour changer le cours des choses pour une g\u00e9n\u00e9ration qui grandit dans la pauvret\u00e9, les abus et les traumatismes.<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/transformiran.com\/fr\/apprendre\/les-enfants-travailleurs-diran\/\">En savoir plus sur les enfants qui travaillent en Iran<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/transformiran.com\/fr\/apprendre\/prostitution-mariages-de-mineurs-et-toxicomanie-en-iran\/\">En savoir plus sur la prostitution, les mariages de mineurs et la toxicomanie en Iran<\/a><\/p>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_1041627511-1024x683.jpg\" alt=\"\" class=\"wp-image-26792\" style=\"aspect-ratio:2\/3;object-fit:cover\" srcset=\"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_1041627511-1024x683.jpg 1024w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_1041627511-300x200.jpg 300w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_1041627511-768x512.jpg 768w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_1041627511-1536x1024.jpg 1536w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_1041627511-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/Iran-women-children-mosque-lite-1024x671.jpeg\" alt=\"\" class=\"wp-image-26778\" style=\"aspect-ratio:4\/3;object-fit:cover\" srcset=\"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/Iran-women-children-mosque-lite-1024x671.jpeg 1024w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/Iran-women-children-mosque-lite-300x197.jpeg 300w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/Iran-women-children-mosque-lite-768x503.jpeg 768w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/Iran-women-children-mosque-lite.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"668\" height=\"1024\" src=\"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_2041272683-668x1024.jpg\" alt=\"\" class=\"wp-image-26799\" style=\"aspect-ratio:2\/3;object-fit:cover\" srcset=\"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_2041272683-668x1024.jpg 668w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_2041272683-196x300.jpg 196w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_2041272683-768x1177.jpg 768w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_2041272683-1003x1536.jpg 1003w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_2041272683-1337x2048.jpg 1337w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_2041272683.jpg 1677w\" sizes=\"auto, (max-width: 668px) 100vw, 668px\" \/><\/figure>\n<\/div>\n<\/div>\n\n<h2 class=\"wp-block-heading\">D\u00e9fis pour les enfants chr\u00e9tiens en Iran<\/h2>\n\n<p class=\"wp-block-paragraph\">La conversion \u00e0 l&#8217;islam est ill\u00e9gale en Iran. Les cons\u00e9quences vont du harc\u00e8lement et des interrogatoires \u00e0 la confiscation des biens, l&#8217;emprisonnement, la torture et la mort. Bien que les enfants ne soient pas confront\u00e9s au bras le plus lourd de la loi, ils sont toujours en danger, ne serait-ce qu&#8217;en exposant la foi de leurs parents.  <\/p>\n\n<p class=\"wp-block-paragraph\">Les enfants chr\u00e9tiens doivent vivre avec l&#8217;inqui\u00e9tude constante de mettre accidentellement leurs parents en danger d&#8217;arrestation. Les enseignements contradictoires entre la maison et l&#8217;\u00e9cole cr\u00e9ent une crise d&#8217;identit\u00e9 et de foi.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00c0 l&#8217;\u00e9cole, mon fils de 10 ans doit \u00e9tudier le Coran et tous les enseignements et textes islamiques qui l&#8217;accompagnent. D\u00e8s le premier cours \u00e0 l&#8217;\u00e9cole, on lui fait \u00e9tudier le Coran. Au fil des ann\u00e9es, ils doivent \u00e9galement r\u00e9citer le &#8220;namaz&#8221; (pri\u00e8res islamiques).  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ils lient toutes sortes de r\u00e9compenses \u00e0 leur m\u00e9morisation et \u00e0 leur r\u00e9citation du namaz, du temps libre aux excursions en passant par la possibilit\u00e9 de faire du sport. Ils doivent \u00e9galement \u00e9tudier les imams et les proph\u00e8tes islamiques, les d\u00e9tails de leur vie et de leur famille jusqu&#8217;\u00e0 leurs enseignements. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&#8217;est tellement difficile pour mon jeune enfant de devoir absorber tout cela et c&#8217;est en contradiction avec tout ce que nous lui enseignons \u00e0 la maison. C&#8217;est particuli\u00e8rement d\u00e9routant lorsqu&#8217;il s&#8217;agit des g\u00e9ants de l&#8217;Ancien Testament tels qu&#8217;Abraham ou Mo\u00efse, qui figurent \u00e9galement dans le Coran, mais avec des r\u00e9cits totalement diff\u00e9rents sur leur vie. <\/p>\n<\/blockquote>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"323\" height=\"227\" src=\"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/Iran-University-Students.jpg\" alt=\"\" class=\"wp-image-26771\" style=\"aspect-ratio:4\/3;object-fit:cover\" srcset=\"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/Iran-University-Students.jpg 323w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/Iran-University-Students-300x211.jpg 300w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"687\" src=\"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/Muslim-woman-prayer-1024x687.jpg\" alt=\"\" class=\"wp-image-26785\" style=\"aspect-ratio:4\/3;object-fit:cover\" srcset=\"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/Muslim-woman-prayer-1024x687.jpg 1024w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/Muslim-woman-prayer-300x201.jpg 300w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/Muslim-woman-prayer-768x516.jpg 768w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/Muslim-woman-prayer-1536x1031.jpg 1536w, https:\/\/transformiran.com\/app\/uploads\/2024\/11\/Muslim-woman-prayer-2048x1375.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n<h2 class=\"wp-block-heading\">Qu&#8217;apprennent les enfants iraniens \u00e0 l&#8217;\u00e9cole ?<\/h2>\n\n<p class=\"wp-block-paragraph\">Outre un m\u00e9lange assez classique d&#8217;arts, de sciences et d&#8217;\u00e9tudes sociales, les enfants iraniens re\u00e7oivent une forte dose de religion et d&#8217;endoctrinement politique dans le cadre de leur \u00e9ducation.<\/p>\n\n<p class=\"wp-block-paragraph\">Chaque matin commence par un chant militaire : &#8220;Mort \u00e0 l&#8217;Am\u00e9rique ! Mort \u00e0 Isra\u00ebl !\nLes murs sont couverts d&#8217;images des ayatollahs et de ceux qui sont morts dans le djihad.\nLes manuels scolaires poursuivent le message en faisant constamment l&#8217;\u00e9loge des imams et des enseignements du proph\u00e8te Mohammad.  <\/p>\n\n<p class=\"wp-block-paragraph\">En outre, chaque enfant doit suivre des cours d&#8217;islam o\u00f9 il apprend \u00e0 r\u00e9citer des versets du Coran, \u00e0 prier son namaz et \u00e0 conna\u00eetre les enseignements et les doctrines de l&#8217;islam.<\/p>\n\n<p class=\"wp-block-paragraph\">Les enfants iraniens r\u00e9fugi\u00e9s en Turquie ne sont pas \u00e9pargn\u00e9s. Bien que le programme ne soit pas aussi agressif, les enfants sont toujours tenus d&#8217;\u00e9tudier l&#8217;islam et de m\u00e9moriser les \u00e9critures et les pri\u00e8res. <\/p>\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-6 wp-block-paragraph\"><strong>Dans ces circonstances difficiles, les communaut\u00e9s chr\u00e9tiennes ont un besoin urgent de soutien, d&#8217;encouragement et d&#8217;orientation.<\/strong><\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Together in Faith: Empowering Young Hearts!\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/mkFDak3pRHc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<div class=\"wp-block-group has-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-white-color has-text-color has-link-color wp-elements-7\">Donnez aux enfants chr\u00e9tiens iraniens les moyens de rester forts dans leur foi !<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Votre soutien peut permettre \u00e0 ces enfants de grandir dans la Parole, de construire des relations durables avec d&#8217;autres croyants et de devenir de solides t\u00e9moins du Christ dans leurs communaut\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ensemble, nous pouvons faire la diff\u00e9rence dans leur vie et dans l&#8217;avenir de l&#8217;Iran.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/transformiran.com\/fr\/donate\/\">Faire un don<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n<h2 class=\"wp-block-heading\">D\u00e9fis pour les enfants chr\u00e9tiens r\u00e9fugi\u00e9s<\/h2>\n\n<p class=\"wp-block-paragraph\">Un nombre croissant d&#8217;enfants r\u00e9fugi\u00e9s iraniens sont confront\u00e9s \u00e0 leurs propres difficult\u00e9s. Ces enfants ont fui leur foyer en raison de la foi ou des convictions politiques de leurs parents, mais leurs camarades continuent de se moquer d&#8217;eux en raison de leur conversion. Ils vivent souvent dans l&#8217;isolement, la pauvret\u00e9 et portent des fardeaux qu&#8217;aucun enfant ne devrait avoir \u00e0 supporter. Ils sont victimes de violences physiques et verbales de la part d&#8217;enfants et d&#8217;enseignants et vivent sous la menace constante d&#8217;une expulsion.   <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Chaque matin, avant d&#8217;aller \u00e0 l&#8217;\u00e9cole, notre fils prie : &#8220;J\u00e9sus, s&#8217;il te pla\u00eet, prot\u00e8ge-moi des coups aujourd&#8217;hui&#8221;.<\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\">La vie des chr\u00e9tiens r\u00e9fugi\u00e9s dans un autre pays musulman est terriblement difficile.  <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Lorsque les enfants vont \u00e0 l&#8217;\u00e9cole ici, ils souffrent d&#8217;une grande d\u00e9tresse \u00e9motionnelle. D\u00e8s que les autres enfants se rendent compte qu&#8217;ils sont chr\u00e9tiens, ils les pers\u00e9cutent &#8211; il n&#8217;y a pas d&#8217;autre mot. M\u00eame les autres enfants les tourmentent.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les enseignants tentent de d\u00e9monter et de discr\u00e9diter le christianisme. Nos enfants qui aiment J\u00e9sus ne sont pas en mesure de faire face \u00e0 cette situation et finissent par d\u00e9battre avec les enseignants. Ces derniers commencent alors \u00e0 leur donner du fil \u00e0 retordre \u00e0 l&#8217;\u00e9cole.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ils n&#8217;ont pas de v\u00e9ritable libert\u00e9 ici. Il y a toujours la menace d&#8217;\u00eatre d\u00e9couvert et pers\u00e9cut\u00e9. Lorsqu&#8217;ils vont au parc ou dans d&#8217;autres lieux publics, ils se font harceler parce qu&#8217;ils sont \u00e9trangers, et encore plus s&#8217;ils sont connus pour \u00eatre chr\u00e9tiens. Aujourd&#8217;hui, les familles sont confront\u00e9es \u00e0 des difficult\u00e9s suppl\u00e9mentaires : elles sont forc\u00e9es de s&#8217;installer dans des camps de r\u00e9fugi\u00e9s, s\u00e9par\u00e9es les unes des autres et expuls\u00e9es vers l&#8217;Iran.   <\/p>\n<\/blockquote>\n\n<h2 class=\"wp-block-heading\">R\u00e9pondre aux besoins des enfants avec la communaut\u00e9 et l&#8217;\u00c9vangile<\/h2>\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-8 wp-block-paragraph\"><strong>Il existe un grand besoin d&#8217;une communaut\u00e9 chr\u00e9tienne o\u00f9 les enfants iraniens (\u00e0 l&#8217;int\u00e9rieur et \u00e0 l&#8217;ext\u00e9rieur de l&#8217;Iran) peuvent trouver de la force dans leur foi, apprendre la Parole de Dieu de mani\u00e8re significative et m\u00e9morable, et savoir qu&#8217;ils ne sont pas seuls.  <\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Ces enfants ont besoin d&#8217;outils pour les aider \u00e0 rester fermes dans leurs croyances, \u00e0 discerner la v\u00e9rit\u00e9 du mensonge et \u00e0 grandir en tant que disciples du Christ capables de partager son amour avec les autres. Si beaucoup a \u00e9t\u00e9 fait pour toucher les adultes iraniens avec l&#8217;\u00c9vangile, il y a encore une lacune importante lorsqu&#8217;il s&#8217;agit de mat\u00e9riel culturellement pertinent sp\u00e9cialement con\u00e7u pour toucher les enfants iraniens. <\/p>\n\n<p class=\"wp-block-paragraph\">Fort d&#8217;une exp\u00e9rience de plusieurs d\u00e9cennies aupr\u00e8s des musulmans de langue farsi, Transform Iran a commenc\u00e9 \u00e0 d\u00e9velopper des ressources de qualit\u00e9 vraiment cibl\u00e9es pour les enfants de 5 \u00e0 12 ans.  <strong>C&#8217;est un \u00e2ge critique o\u00f9 les enfants forment leur vision du monde et font des choix qui d\u00e9terminent leur avenir et leur sens de l&#8217;identit\u00e9.<\/strong>  Avec environ 10 millions d&#8217;enfants iraniens dans cette tranche d&#8217;\u00e2ge, il s&#8217;agit d&#8217;une opportunit\u00e9 cruciale pour le minist\u00e8re.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/transformiran.com\/fr\/notre-travail\/atteindre-les-enfants\/\">En savoir plus sur notre travail aupr\u00e8s des enfants d&#8217;Iran<\/a><\/p>\n\n<div class=\"wp-block-group has-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-white-color has-text-color has-link-color wp-elements-9\">Donnez aux enfants chr\u00e9tiens iraniens les moyens de rester forts dans leur foi !<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Votre soutien peut permettre \u00e0 ces enfants de grandir dans la Parole, de construire des relations durables avec d&#8217;autres croyants et de devenir de solides t\u00e9moins du Christ dans leurs communaut\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ensemble, nous pouvons faire la diff\u00e9rence dans leur vie et dans l&#8217;avenir de l&#8217;Iran.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/transformiran.com\/fr\/donate\/\">Faire un don<\/a><\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En Iran, de nombreux enfants subissent des \u00e9preuves inimaginables &#8211; des circonstances auxquelles aucun enfant ne devrait \u00eatre confront\u00e9. De plus, les enfants chr\u00e9tiens iraniens et les r\u00e9fugi\u00e9s subissent des pers\u00e9cutions quotidiennes. D\u00e9couvrez comment vous pouvez nous aider \u00e0 avoir un impact durable sur leur vie.    <\/p>\n","protected":false},"author":6,"featured_media":26809,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"om_disable_all_campaigns":false,"_mi_skip_tracking":false,"footnotes":""},"categories":[312],"tags":[286,284,298,305],"class_list":["post-26816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apprendre","tag-gouvernement","tag-liran","tag-la-jeunesse","tag-les-enfants"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les d\u00e9fis auxquels sont confront\u00e9s les enfants iraniens aujourd&#039;hui - Transform Iran<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les d\u00e9fis auxquels sont confront\u00e9s les enfants iraniens aujourd&#039;hui - Transform Iran\" \/>\n<meta property=\"og:description\" content=\"En Iran, de nombreux enfants subissent des \u00e9preuves inimaginables - des circonstances auxquelles aucun enfant ne devrait \u00eatre confront\u00e9. De plus, les enfants chr\u00e9tiens iraniens et les r\u00e9fugi\u00e9s subissent des pers\u00e9cutions quotidiennes. D\u00e9couvrez comment vous pouvez nous aider \u00e0 avoir un impact durable sur leur vie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/\" \/>\n<meta property=\"og:site_name\" content=\"Transform Iran\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/222MinistriesUSAInc\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-08T15:53:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-08T14:56:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_300011561-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ashleigh Bedford\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@222minint\" \/>\n<meta name=\"twitter:site\" content=\"@222minint\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ashleigh Bedford\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\\\/\"},\"author\":{\"name\":\"Ashleigh Bedford\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#\\\/schema\\\/person\\\/901d817bcb841b949dbba5fa2886bfe3\"},\"headline\":\"Les d\u00e9fis auxquels sont confront\u00e9s les enfants iraniens aujourd&#8217;hui\",\"datePublished\":\"2024-11-08T15:53:56+00:00\",\"dateModified\":\"2025-04-08T14:56:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\\\/\"},\"wordCount\":1716,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2024\\\/11\\\/shutterstock_300011561-scaled.jpg\",\"keywords\":[\"Gouvernement\",\"L'Iran\",\"La jeunesse\",\"Les enfants\"],\"articleSection\":[\"Apprendre\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\\\/\",\"url\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\\\/\",\"name\":\"Les d\u00e9fis auxquels sont confront\u00e9s les enfants iraniens aujourd'hui - Transform Iran\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2024\\\/11\\\/shutterstock_300011561-scaled.jpg\",\"datePublished\":\"2024-11-08T15:53:56+00:00\",\"dateModified\":\"2025-04-08T14:56:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2024\\\/11\\\/shutterstock_300011561-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2024\\\/11\\\/shutterstock_300011561-scaled.jpg\",\"width\":3000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les d\u00e9fis auxquels sont confront\u00e9s les enfants iraniens aujourd&#8217;hui\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/\",\"name\":\"Transform Iran\",\"description\":\"Bringing the love and power of Christ to Iran - and beyond\",\"publisher\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#organization\",\"name\":\"Transform Iran\",\"url\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2022\\\/11\\\/logo_grey.jpg\",\"contentUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2022\\\/11\\\/logo_grey.jpg\",\"width\":528,\"height\":90,\"caption\":\"Transform Iran\"},\"image\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/222MinistriesUSAInc\",\"https:\\\/\\\/x.com\\\/222minint\",\"https:\\\/\\\/www.instagram.com\\\/222ministriesinternational\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#\\\/schema\\\/person\\\/901d817bcb841b949dbba5fa2886bfe3\",\"name\":\"Ashleigh Bedford\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g\",\"caption\":\"Ashleigh Bedford\"},\"url\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/author\\\/ashleigh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les d\u00e9fis auxquels sont confront\u00e9s les enfants iraniens aujourd'hui - Transform Iran","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/","og_locale":"fr_FR","og_type":"article","og_title":"Les d\u00e9fis auxquels sont confront\u00e9s les enfants iraniens aujourd'hui - Transform Iran","og_description":"En Iran, de nombreux enfants subissent des \u00e9preuves inimaginables - des circonstances auxquelles aucun enfant ne devrait \u00eatre confront\u00e9. De plus, les enfants chr\u00e9tiens iraniens et les r\u00e9fugi\u00e9s subissent des pers\u00e9cutions quotidiennes. D\u00e9couvrez comment vous pouvez nous aider \u00e0 avoir un impact durable sur leur vie.","og_url":"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/","og_site_name":"Transform Iran","article_publisher":"https:\/\/www.facebook.com\/222MinistriesUSAInc","article_published_time":"2024-11-08T15:53:56+00:00","article_modified_time":"2025-04-08T14:56:32+00:00","og_image":[{"width":3000,"height":2000,"url":"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_300011561-scaled.jpg","type":"image\/jpeg"}],"author":"Ashleigh Bedford","twitter_card":"summary_large_image","twitter_creator":"@222minint","twitter_site":"@222minint","twitter_misc":{"Written by":"Ashleigh Bedford","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/#article","isPartOf":{"@id":"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/"},"author":{"name":"Ashleigh Bedford","@id":"https:\/\/transformiran.com\/fr\/#\/schema\/person\/901d817bcb841b949dbba5fa2886bfe3"},"headline":"Les d\u00e9fis auxquels sont confront\u00e9s les enfants iraniens aujourd&#8217;hui","datePublished":"2024-11-08T15:53:56+00:00","dateModified":"2025-04-08T14:56:32+00:00","mainEntityOfPage":{"@id":"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/"},"wordCount":1716,"commentCount":0,"publisher":{"@id":"https:\/\/transformiran.com\/fr\/#organization"},"image":{"@id":"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/#primaryimage"},"thumbnailUrl":"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_300011561-scaled.jpg","keywords":["Gouvernement","L'Iran","La jeunesse","Les enfants"],"articleSection":["Apprendre"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/","url":"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/","name":"Les d\u00e9fis auxquels sont confront\u00e9s les enfants iraniens aujourd'hui - Transform Iran","isPartOf":{"@id":"https:\/\/transformiran.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/#primaryimage"},"image":{"@id":"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/#primaryimage"},"thumbnailUrl":"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_300011561-scaled.jpg","datePublished":"2024-11-08T15:53:56+00:00","dateModified":"2025-04-08T14:56:32+00:00","breadcrumb":{"@id":"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/#primaryimage","url":"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_300011561-scaled.jpg","contentUrl":"https:\/\/transformiran.com\/app\/uploads\/2024\/11\/shutterstock_300011561-scaled.jpg","width":3000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/transformiran.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Les d\u00e9fis auxquels sont confront\u00e9s les enfants iraniens aujourd&#8217;hui"}]},{"@type":"WebSite","@id":"https:\/\/transformiran.com\/fr\/#website","url":"https:\/\/transformiran.com\/fr\/","name":"Transform Iran","description":"Bringing the love and power of Christ to Iran - and beyond","publisher":{"@id":"https:\/\/transformiran.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transformiran.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/transformiran.com\/fr\/#organization","name":"Transform Iran","url":"https:\/\/transformiran.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/transformiran.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/transformiran.com\/app\/uploads\/2022\/11\/logo_grey.jpg","contentUrl":"https:\/\/transformiran.com\/app\/uploads\/2022\/11\/logo_grey.jpg","width":528,"height":90,"caption":"Transform Iran"},"image":{"@id":"https:\/\/transformiran.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/222MinistriesUSAInc","https:\/\/x.com\/222minint","https:\/\/www.instagram.com\/222ministriesinternational\/"]},{"@type":"Person","@id":"https:\/\/transformiran.com\/fr\/#\/schema\/person\/901d817bcb841b949dbba5fa2886bfe3","name":"Ashleigh Bedford","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g","caption":"Ashleigh Bedford"},"url":"https:\/\/transformiran.com\/fr\/author\/ashleigh\/"}]}},"_links":{"self":[{"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/posts\/26816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/comments?post=26816"}],"version-history":[{"count":0,"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/posts\/26816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/media\/26809"}],"wp:attachment":[{"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/media?parent=26816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/categories?post=26816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/tags?post=26816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}