{"id":30860,"date":"2025-05-07T05:21:27","date_gmt":"2025-05-07T04:21:27","guid":{"rendered":"https:\/\/transformiran.com\/non-classifiee\/sans-silence-leglise-clandestine-en-iran\/"},"modified":"2026-08-25T17:00:00","modified_gmt":"2026-08-25T16:00:00","slug":"sans-silence-leglise-clandestine-en-iran","status":"publish","type":"post","link":"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/","title":{"rendered":"Sans silence : L&#8217;\u00e9glise souterraine d&#8217;Iran"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\">Curieux de savoir \u00e0 quoi ressemble vraiment la vie des croyants clandestins en Iran ? Cet article vous offre un aper\u00e7u de leur monde cach\u00e9. <\/p>\n\n<h2 class=\"wp-block-heading\">L&#8217;\u00c9glise secr\u00e8te d&#8217;Iran risque tout pour le Christ<\/h2>\n\n<p class=\"wp-block-paragraph\">L&#8217;\u00c9glise clandestine d&#8217;Iran ne ressemble \u00e0 aucune autre. Elle est dynamique, courageuse et se d\u00e9veloppe rapidement sous la menace constante de la pers\u00e9cution. Chaque jour, les disciples de J\u00e9sus font des choix difficiles : risquer d&#8217;\u00eatre d\u00e9masqu\u00e9s ou rester silencieux, se r\u00e9unir ou rester isol\u00e9s, faire confiance \u00e0 des \u00e9trangers ou garder leur foi en secret.  <\/p>\n\n<h3 class=\"wp-block-heading\">Derri\u00e8re les portes closes<\/h3>\n\n<p class=\"wp-block-paragraph\">Sans b\u00e2timents officiels, les croyants se r\u00e9unissent en petits groupes, g\u00e9n\u00e9ralement \u00e0 l&#8217;int\u00e9rieur des maisons. Ils c\u00e9l\u00e8brent le culte, \u00e9tudient la Bible et prient ensemble. Ces \u00e9glises de maison sont des communaut\u00e9s intimes, profond\u00e9ment relationnelles, o\u00f9 la confiance est essentielle et o\u00f9 chaque nouveau membre est consid\u00e9r\u00e9 dans la pri\u00e8re.  <\/p>\n\n<h3 class=\"wp-block-heading\">Vivre sous une menace constante<\/h3>\n\n<p class=\"wp-block-paragraph\">En Iran, suivre J\u00e9sus peut \u00eatre synonyme d&#8217;arrestation, de torture, d&#8217;emprisonnement, voire pire. Malgr\u00e9 la surveillance du gouvernement, les raids et les sanctions s\u00e9v\u00e8res, l&#8217;\u00e9glise clandestine se d\u00e9veloppe, aliment\u00e9e par une faim profonde de v\u00e9rit\u00e9 et de rencontres personnelles avec le Christ. <\/p>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"943\" height=\"1022\" src=\"https:\/\/transformiran.com\/app\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-06.22.19_18b7f68f.jpg\" alt=\"\" class=\"wp-image-30716\" style=\"aspect-ratio:4\/3;object-fit:cover\" srcset=\"https:\/\/transformiran.com\/app\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-06.22.19_18b7f68f.jpg 943w, https:\/\/transformiran.com\/app\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-06.22.19_18b7f68f-277x300.jpg 277w, https:\/\/transformiran.com\/app\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-06.22.19_18b7f68f-768x832.jpg 768w\" sizes=\"auto, (max-width: 943px) 100vw, 943px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"678\" height=\"559\" src=\"https:\/\/transformiran.com\/app\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-06.22.19_f0738a40.jpg\" alt=\"\" class=\"wp-image-30723\" style=\"aspect-ratio:4\/3;object-fit:cover\" srcset=\"https:\/\/transformiran.com\/app\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-06.22.19_f0738a40.jpg 678w, https:\/\/transformiran.com\/app\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-06.22.19_f0738a40-300x247.jpg 300w\" sizes=\"auto, (max-width: 678px) 100vw, 678px\" \/><\/figure>\n<\/div>\n<\/div>\n\n<h3 class=\"wp-block-heading\">Les enfants pris entre la propagande et la foi<\/h3>\n\n<p class=\"wp-block-paragraph\">En Iran, la propagande d&#8217;\u00c9tat inculque aux enfants la violence, la haine et l&#8217;ob\u00e9issance aveugle. Ils apprennent que leur voix n&#8217;a aucune valeur et que des groupes entiers de personnes sont moins dignes d&#8217;int\u00e9r\u00eat. Les enfants chr\u00e9tiens sont confront\u00e9s \u00e0 la menace de la pers\u00e9cution et au lourd fardeau de risquer la s\u00e9curit\u00e9 de leur famille. M\u00eame \u00e0 un jeune \u00e2ge, ils doivent soigneusement naviguer entre des visions du monde oppos\u00e9es, entre la propagande qu&#8217;on leur enseigne et la v\u00e9rit\u00e9 qu&#8217;ils ont trouv\u00e9e dans le Christ.   <\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/transformiran.com\/fr\/apprendre\/les-defis-auxquels-sont-confrontes-les-enfants-iraniens-aujourdhui\/\">En savoir plus sur les d\u00e9fis quotidiens auxquels sont confront\u00e9s les enfants iraniens<\/a><\/p>\n\n<h3 class=\"wp-block-heading\">La formation de disciples alimente une croissance r\u00e9siliente<\/h3>\n\n<p class=\"wp-block-paragraph\">L&#8217;\u00e9glise clandestine iranienne prosp\u00e8re gr\u00e2ce \u00e0 un engagement profond en faveur de la <a href=\"https:\/\/transformiran.com\/fr\/notre-travail\/formation-de-disciple\/\">formation de disciples<\/a>. Les nouveaux croyants sont encadr\u00e9s chaque semaine et on leur apprend \u00e0 rester forts. Transform Iran organise des voyages de discipulat individuels d&#8217;une dur\u00e9e d&#8217;un an, en utilisant des m\u00e9thodes de communication s\u00e9curis\u00e9es pour construire de nouveaux chr\u00e9tiens, m\u00eame sous la menace.  <\/p>\n\n<h3 class=\"wp-block-heading\">J\u00e9sus dans les failles<\/h3>\n\n<p class=\"wp-block-paragraph\">Malgr\u00e9 l&#8217;<a href=\"https:\/\/transformiran.com\/fr\/apprendre\/controle-des-medias-en-iran\/\">interdiction<\/a> stricte des m\u00e9dias chr\u00e9tiens et autres m\u00e9dias ext\u00e9rieurs par le gouvernement iranien, les histoires miraculeuses abondent ! On ne peut emp\u00eacher J\u00e9sus d&#8217;appara\u00eetre dans des r\u00eaves et des visions, d&#8217;exaucer les pri\u00e8res des demandeurs ou de transformer des vies par la <a href=\"https:\/\/transformiran.com\/fr\/impact-fr\/une-histoire-de-guerison-de-foi-et-de-communaute-ecclesiale-numerique\/\">gu\u00e9rison<\/a>.   <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Ceux qui le rencontrent directement deviennent des t\u00e9moins imparables, partageant leur nouvelle esp\u00e9rance m\u00eame si cela peut leur co\u00fbter tout.<\/p>\n<\/blockquote>\n\n<h3 class=\"wp-block-heading\">Pas de chr\u00e9tiens ti\u00e8des ici<\/h3>\n\n<p class=\"wp-block-paragraph\">Les Iraniens sont \u00e9puis\u00e9s par des d\u00e9cennies d&#8217;oppression. M\u00eame les chercheurs sont pr\u00eats \u00e0 tout risquer pour la libert\u00e9 offerte par le Christ. Chaque croyant raconte qu&#8217;il a \u00e9t\u00e9 transform\u00e9 par le Christ et qu&#8217;il a \u00e9t\u00e9 rempli d&#8217;une joie qu&#8217;il ne peut contenir. En Iran, il n&#8217;y a pas de chr\u00e9tiens ti\u00e8des &#8211; seulement des disciples passionn\u00e9s qui comprennent le co\u00fbt de la vie de disciple et l&#8217;embrassent avec audace.   <\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/transformiran.com\/fr\/impact-fr\/comment-le-nom-de-jesus-a-change-lhistoire-de-grace\/\">Lisez comment le nom de J\u00e9sus a chang\u00e9 l&#8217;histoire de Grace ; dans l&#8217;ann\u00e9e qui a suivi sa rencontre avec le Christ, elle a partag\u00e9 l&#8217;\u00c9vangile avec 600 personnes.<\/a><\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"The Risk of Sharing Your Faith in Iran (60-Second Reel)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/C2pdLblzp2Q?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<div class=\"wp-block-group has-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-white-color has-text-color has-link-color wp-elements-1\">Recevez notre lettre d&#8217;information<\/h2>\n\n\n\n<p class=\"has-white-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\">Restez au courant de ce que Dieu fait en Iran aujourd&#8217;hui ! Obtenez les derniers points de pri\u00e8re, les avanc\u00e9es des projets et les possibilit\u00e9s de s&#8217;impliquer. <\/p>\n\n\n<script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform-theme gform-theme--foundation gform-theme--framework gform-theme--orbital' data-form-theme='orbital' data-form-index='0' id='gform_wrapper_1' ><style>#gform_wrapper_1[data-form-index=\"0\"].gform-theme,[data-parent-form=\"1_0\"]{--gf-color-primary: #204ce5;--gf-color-primary-rgb: 32, 76, 229;--gf-color-primary-contrast: #fff;--gf-color-primary-contrast-rgb: 255, 255, 255;--gf-color-primary-darker: #001AB3;--gf-color-primary-lighter: #527EFF;--gf-color-secondary: #fff;--gf-color-secondary-rgb: 255, 255, 255;--gf-color-secondary-contrast: #112337;--gf-color-secondary-contrast-rgb: 17, 35, 55;--gf-color-secondary-darker: #F5F5F5;--gf-color-secondary-lighter: #FFFFFF;--gf-color-out-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-out-ctrl-light-rgb: 17, 35, 55;--gf-color-out-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-out-ctrl-light-lighter: #F5F5F5;--gf-color-out-ctrl-dark: #585e6a;--gf-color-out-ctrl-dark-rgb: 88, 94, 106;--gf-color-out-ctrl-dark-darker: #112337;--gf-color-out-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-color-in-ctrl: #fff;--gf-color-in-ctrl-rgb: 255, 255, 255;--gf-color-in-ctrl-contrast: #112337;--gf-color-in-ctrl-contrast-rgb: 17, 35, 55;--gf-color-in-ctrl-darker: #F5F5F5;--gf-color-in-ctrl-lighter: #FFFFFF;--gf-color-in-ctrl-primary: #204ce5;--gf-color-in-ctrl-primary-rgb: 32, 76, 229;--gf-color-in-ctrl-primary-contrast: #fff;--gf-color-in-ctrl-primary-contrast-rgb: 255, 255, 255;--gf-color-in-ctrl-primary-darker: #001AB3;--gf-color-in-ctrl-primary-lighter: #527EFF;--gf-color-in-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-in-ctrl-light-rgb: 17, 35, 55;--gf-color-in-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-in-ctrl-light-lighter: #F5F5F5;--gf-color-in-ctrl-dark: #585e6a;--gf-color-in-ctrl-dark-rgb: 88, 94, 106;--gf-color-in-ctrl-dark-darker: #112337;--gf-color-in-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-radius: 3px;--gf-font-size-secondary: 14px;--gf-font-size-tertiary: 13px;--gf-icon-ctrl-number: url(\"data:image\/svg+xml,%3Csvg width='8' height='14' viewBox='0 0 8 14' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M4 0C4.26522 5.96046e-08 4.51957 0.105357 4.70711 0.292893L7.70711 3.29289C8.09763 3.68342 8.09763 4.31658 7.70711 4.70711C7.31658 5.09763 6.68342 5.09763 6.29289 4.70711L4 2.41421L1.70711 4.70711C1.31658 5.09763 0.683417 5.09763 0.292893 4.70711C-0.0976311 4.31658 -0.097631 3.68342 0.292893 3.29289L3.29289 0.292893C3.48043 0.105357 3.73478 0 4 0ZM0.292893 9.29289C0.683417 8.90237 1.31658 8.90237 1.70711 9.29289L4 11.5858L6.29289 9.29289C6.68342 8.90237 7.31658 8.90237 7.70711 9.29289C8.09763 9.68342 8.09763 10.3166 7.70711 10.7071L4.70711 13.7071C4.31658 14.0976 3.68342 14.0976 3.29289 13.7071L0.292893 10.7071C-0.0976311 10.3166 -0.0976311 9.68342 0.292893 9.29289Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-select: url(\"data:image\/svg+xml,%3Csvg width='10' height='6' viewBox='0 0 10 6' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M0.292893 0.292893C0.683417 -0.097631 1.31658 -0.097631 1.70711 0.292893L5 3.58579L8.29289 0.292893C8.68342 -0.0976311 9.31658 -0.0976311 9.70711 0.292893C10.0976 0.683417 10.0976 1.31658 9.70711 1.70711L5.70711 5.70711C5.31658 6.09763 4.68342 6.09763 4.29289 5.70711L0.292893 1.70711C-0.0976311 1.31658 -0.0976311 0.683418 0.292893 0.292893Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-search: url(\"data:image\/svg+xml,%3Csvg width='640' height='640' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath d='M256 128c-70.692 0-128 57.308-128 128 0 70.691 57.308 128 128 128 70.691 0 128-57.309 128-128 0-70.692-57.309-128-128-128zM64 256c0-106.039 85.961-192 192-192s192 85.961 192 192c0 41.466-13.146 79.863-35.498 111.248l154.125 154.125c12.496 12.496 12.496 32.758 0 45.254s-32.758 12.496-45.254 0L367.248 412.502C335.862 434.854 297.467 448 256 448c-106.039 0-192-85.962-192-192z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-label-space-y-secondary: var(--gf-label-space-y-md-secondary);--gf-ctrl-border-color: #686e77;--gf-ctrl-size: var(--gf-ctrl-size-md);--gf-ctrl-label-color-primary: #112337;--gf-ctrl-label-color-secondary: #112337;--gf-ctrl-choice-size: var(--gf-ctrl-choice-size-md);--gf-ctrl-checkbox-check-size: var(--gf-ctrl-checkbox-check-size-md);--gf-ctrl-radio-check-size: var(--gf-ctrl-radio-check-size-md);--gf-ctrl-btn-font-size: var(--gf-ctrl-btn-font-size-md);--gf-ctrl-btn-padding-x: var(--gf-ctrl-btn-padding-x-md);--gf-ctrl-btn-size: var(--gf-ctrl-btn-size-md);--gf-ctrl-btn-border-color-secondary: #686e77;--gf-ctrl-file-btn-bg-color-hover: #EBEBEB;--gf-field-img-choice-size: var(--gf-field-img-choice-size-md);--gf-field-img-choice-card-space: var(--gf-field-img-choice-card-space-md);--gf-field-img-choice-check-ind-size: var(--gf-field-img-choice-check-ind-size-md);--gf-field-img-choice-check-ind-icon-size: var(--gf-field-img-choice-check-ind-icon-size-md);--gf-field-pg-steps-number-color: rgba(17, 35, 55, 0.8);}<\/style><div id='gf_1' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_1' id='gform_1'  action='\/fr\/wp-json\/wp\/v2\/posts\/30860#gf_1' data-formid='1' novalidate><div class='gf_invisible ginput_recaptchav3' data-sitekey='6LeOJgUrAAAAAPuuAflulrZo7spbjlHo45naz4Z3' data-tabindex='0'><input id=\"input_d6940e429b33b630150a5335bca4b629\" class=\"gfield_recaptcha_response\" type=\"hidden\" name=\"input_d6940e429b33b630150a5335bca4b629\" value=\"\"\/><\/div>\n                        <div class='gform-body gform_body'><div id='gform_fields_1' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_1_1\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-third field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_1'>First Name<\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_1_1' type='text' value='' class='large'    placeholder='First Name'  aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_1_5\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-third field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_5'>Last Name<\/label><div class='ginput_container ginput_container_text'><input name='input_5' id='input_1_5' type='text' value='' class='large'    placeholder='Last Name'  aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_1_4\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-third field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_4'>Email<\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_4' id='input_1_4' type='email' value='' class='large'   placeholder='Email'  aria-invalid=\"false\"  \/>\n                        <\/div><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_1' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Sign up'  \/> <input type='hidden' name='gform_ajax' value='form_id=1&amp;title=&amp;description=&amp;tabindex=0&amp;theme=orbital&amp;styles={&quot;inputPrimaryColor&quot;:&quot;#204ce5&quot;}&amp;hash=fc2cdfee64d0ed64edfd126c6336bc8e' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_1' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_1' id='gform_theme_1' value='orbital' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_1' id='gform_style_settings_1' value='{&quot;inputPrimaryColor&quot;:&quot;#204ce5&quot;}' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_1' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='1' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='y1ntW+uREsiKkl3V2aRn9i1z8yXqh29qSbcI9xjqwAuxRDT22c+tHyBs\/sYeUT4ouF077voVWh5dZW\/3nbl\/\/xokyAQZ+Crq928a8cyBT90ubaY=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_1' value='WyJbXSIsIjYxZTg1MmUwMmZjNzkzZTQxZWUyZDJjMjJjMWJmZjJiIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_1' id='gform_target_page_number_1' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_1' id='gform_source_page_number_1' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_1' id='gform_ajax_frame_1' title='This iframe contains the logic required to handle Ajax powered Gravity Forms.'><\/iframe>\n\t\t                <script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 1, 'https:\/\/transformiran.com\/app\/plugins\/gravityforms\/images\/spinner.svg', false );jQuery('#gform_ajax_frame_1').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_1');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_1').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_1').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_1').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_1').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_1').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_1').val();gformInitSpinner( 1, 'https:\/\/transformiran.com\/app\/plugins\/gravityforms\/images\/spinner.svg', false );jQuery(document).trigger('gform_page_loaded', [1, current_page]);window['gf_submitting_1'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_1').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_1').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [1]);window['gf_submitting_1'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_1').text());}else{jQuery('#gform_1').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"1\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_1\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_1\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_1\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 1, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n<\/div><\/div>\n\n<h3 class=\"wp-block-heading\"><strong>Des t\u00e9moins audacieux dans un pays hostile<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Malgr\u00e9 les dangers, les chr\u00e9tiens iraniens <a href=\"https:\/\/transformiran.com\/fr\/impact-fr\/une-jeune-musulmane-pardonnee-decouvre-sa-valeur-en-christ\/\">partagent souvent leur foi<\/a> sans crainte avec leur famille, leurs amis et m\u00eame des \u00e9trangers.  <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Leurs vies sont empreintes de courage et de r\u00e9silience, t\u00e9moignant avec force de l&#8217;amour ind\u00e9fectible de Dieu pour le peuple iranien.<\/p>\n<\/blockquote>\n\n<h3 class=\"wp-block-heading\"><strong>L&#8217;\u00e9glise num\u00e9rique pour les isol\u00e9s<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Transform Iran exploite la puissance des satellites et des m\u00e9dias pour atteindre les chercheurs et les croyants dans tout le pays. Gr\u00e2ce \u00e0 des plateformes en ligne s\u00e9curis\u00e9es, \u00e0 un contenu num\u00e9rique sp\u00e9cialement cr\u00e9\u00e9, \u00e0 des rassemblements virtuels et \u00e0 des salles de pri\u00e8re, les croyants isol\u00e9s qui doivent rester anonymes peuvent n\u00e9anmoins grandir dans la foi et la communaut\u00e9. L <a href=\"https:\/\/transformiran.com\/fr\/notre-travail\/eglise-numerique\/\">&#8216;\u00e9glise num\u00e9rique <\/a>est devenue une bou\u00e9e de sauvetage pour de nombreuses personnes qui, autrement, seraient compl\u00e8tement coup\u00e9es de la communion. <\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Sauvegarder les croyants et construire l&#8217;avenir<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Transform Iran prend des mesures essentielles pour prot\u00e9ger l&#8217;\u00e9glise clandestine. Nous proposons des formations \u00e0 la s\u00e9curit\u00e9 et des plateformes de communication crypt\u00e9es, des connaissances sur le contr\u00f4le minutieux des nouveaux croyants et, si n\u00e9cessaire, un <a href=\"https:\/\/transformiran.com\/fr\/notre-travail\/refugies-et-eglise-persecutee\/\">soutien pratique<\/a> aux croyants qui doivent fuir, y compris une relocalisation d&#8217;urgence, un abri et les besoins essentiels. <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Nous aidons ceux qui ont \u00e9t\u00e9 contraints de fuir \u00e0 reconstruire leur vie, \u00e0 rester enracin\u00e9s dans le Christ et \u00e0 poursuivre la mission.<\/p>\n<\/blockquote>\n\n<h2 class=\"wp-block-heading\">Aux c\u00f4t\u00e9s de l&#8217;\u00c9glise souterraine d&#8217;Iran<\/h2>\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Vos pri\u00e8res sont essentielles pour soutenir l&#8217;\u00e9glise clandestine en Iran. Voici quelques moyens sp\u00e9cifiques de prier : <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Protection des croyants et des \u00e9glises de maison<\/strong>: Priez pour la s\u00e9curit\u00e9 de tous les rassemblements clandestins, car les croyants sont constamment expos\u00e9s au risque de surveillance, de raids et d&#8217;arrestation. Priez pour que Dieu assure la protection divine de ces r\u00e9unions secr\u00e8tes. <\/li>\n\n\n\n<li><strong>Force pour les enfants chr\u00e9tiens<\/strong>: Priez pour les enfants qui sont confront\u00e9s \u00e0 une pers\u00e9cution et \u00e0 une pression intenses \u00e0 l&#8217;\u00e9cole et \u00e0 la maison. Demandez \u00e0 Dieu de leur donner du courage, de la paix et un lien profond avec sa v\u00e9rit\u00e9 alors qu&#8217;ils naviguent dans un conflit difficile entre la propagande impos\u00e9e par l&#8217;\u00c9tat et leur foi en J\u00e9sus. <\/li>\n\n\n\n<li><strong>Sagesse et audace pour les responsables<\/strong>: Les responsables d&#8217;\u00e9glise et les mentors de la formation de disciples sont essentiels pour renforcer les croyants. Priez pour qu&#8217;ils aient la sagesse et le discernement lorsqu&#8217;ils dirigent de nouveaux chr\u00e9tiens, ainsi que l&#8217;audace de continuer \u00e0 partager l&#8217;Evangile malgr\u00e9 les risques. <\/li>\n\n\n\n<li><strong>Endurance pour les nouveaux croyants sous pression<\/strong>: De nombreux nouveaux croyants sont confront\u00e9s \u00e0 une dure pers\u00e9cution. Priez pour leur endurance et leur foi profond\u00e9ment enracin\u00e9e alors qu&#8217;ils progressent dans leur marche avec le Christ. Priez pour que leurs familles et leurs communaut\u00e9s r\u00e9agissent positivement \u00e0 l&#8217;Evangile. Qu&#8217;ils restent forts malgr\u00e9 les cons\u00e9quences.   <\/li>\n\n\n\n<li><strong>Gu\u00e9rison pour ceux qui souffrent<\/strong>: De nombreux chr\u00e9tiens iraniens ont subi des traumatismes physiques et \u00e9motionnels en raison de leur foi. Priez pour la gu\u00e9rison, la paix et la restauration de ceux qui ont \u00e9t\u00e9 touch\u00e9s par la violence, l&#8217;emprisonnement ou les abus. <\/li>\n\n\n\n<li><strong>Croissance des communaut\u00e9s eccl\u00e9siales num\u00e9riques<\/strong>: Priez pour le nombre croissant de croyants isol\u00e9s qui s&#8217;appuient sur des plateformes num\u00e9riques pour rester en contact et grandir dans leur foi. Demandez \u00e0 Dieu de continuer \u00e0 b\u00e9nir ces rassemblements virtuels, et qu&#8217;ils puissent apporter de l&#8217;espoir, des liens et une croissance spirituelle \u00e0 ceux qui doivent rester anonymes. <\/li>\n\n\n\n<li><strong>Provision pour ceux qui doivent fuir<\/strong>: Pour les croyants qui sont contraints de fuir \u00e0 cause de la pers\u00e9cution, priez pour qu&#8217;ils aient de quoi s&#8217;abriter, se mettre en s\u00e9curit\u00e9 ou se reloger. Priez pour que ces personnes continuent \u00e0 retrouver le chemin des communaut\u00e9s chr\u00e9tiennes qui les soutiennent et pour que leur foi reste forte. <\/li>\n\n\n\n<li><strong>Faim de v\u00e9rit\u00e9<\/strong>: Priez pour la faim spirituelle qui persiste en Iran. Alors que de nombreux Iraniens se lassent de l&#8217;oppression et recherchent une v\u00e9rit\u00e9 plus profonde, demandez \u00e0 Dieu de les conduire au Christ, de leur offrir des rencontres qui changent leur vie et de renforcer l&#8217;\u00e9glise clandestine. <\/li>\n<\/ul>\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Participez \u00e0 l&#8217;histoire que Dieu \u00e9crit en Iran ! <a href=\"https:\/\/transformiran.com\/fr\/inscription-au-bulletin-dinformation\/\">Inscrivez-vous \u00e0 nos bulletins d&#8217;information mensuels<\/a>.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/transformiran.com\/fr\/notre-travail\/church-planting\/\">En savoir plus sur l&#8217;implantation d&#8217;\u00e9glises en Iran<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/transformiran.com\/fr\/notre-travail\/aider-ceux-qui-souffrent\/\">Lisez \u00e0 propos de l&#8217;\u00e9glise en mission pour aider les personnes souffrantes<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Curieux de savoir \u00e0 quoi ressemble vraiment la vie des croyants clandestins en Iran ? Cet article vous offre un aper\u00e7u de leur monde cach\u00e9. <\/p>\n","protected":false},"author":6,"featured_media":40030,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"om_disable_all_campaigns":false,"_mi_skip_tracking":false,"footnotes":""},"categories":[312],"tags":[306,334,293,286,289],"class_list":["post-30860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apprendre","tag-eglise","tag-eglise-persecutee","tag-formation-de-disciple","tag-gouvernement","tag-transformation-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sans silence : L&#039;\u00e9glise souterraine d&#039;Iran - Transform Iran<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sans silence : L&#039;\u00e9glise souterraine d&#039;Iran - Transform Iran\" \/>\n<meta property=\"og:description\" content=\"Curieux de savoir \u00e0 quoi ressemble vraiment la vie des croyants clandestins en Iran ? Cet article vous offre un aper\u00e7u de leur monde cach\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/\" \/>\n<meta property=\"og:site_name\" content=\"Transform Iran\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/222MinistriesUSAInc\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-07T04:21:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-25T16:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transformiran.com\/app\/uploads\/2025\/05\/PRAYER-SAFE-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1689\" \/>\n\t<meta property=\"og:image:height\" content=\"3000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ashleigh Bedford\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@222minint\" \/>\n<meta name=\"twitter:site\" content=\"@222minint\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ashleigh Bedford\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/sans-silence-leglise-clandestine-en-iran\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/sans-silence-leglise-clandestine-en-iran\\\/\"},\"author\":{\"name\":\"Ashleigh Bedford\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#\\\/schema\\\/person\\\/901d817bcb841b949dbba5fa2886bfe3\"},\"headline\":\"Sans silence : L&#8217;\u00e9glise souterraine d&#8217;Iran\",\"datePublished\":\"2025-05-07T04:21:27+00:00\",\"dateModified\":\"2026-08-25T16:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/sans-silence-leglise-clandestine-en-iran\\\/\"},\"wordCount\":1444,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/sans-silence-leglise-clandestine-en-iran\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2025\\\/05\\\/PRAYER-SAFE-scaled.jpg\",\"keywords\":[\"\u00c9glise\",\"\u00c9glise pers\u00e9cut\u00e9e\",\"Formation de disciple\",\"Gouvernement\",\"Transformation\"],\"articleSection\":[\"Apprendre\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/sans-silence-leglise-clandestine-en-iran\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/sans-silence-leglise-clandestine-en-iran\\\/\",\"url\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/sans-silence-leglise-clandestine-en-iran\\\/\",\"name\":\"Sans silence : L'\u00e9glise souterraine d'Iran - Transform Iran\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/sans-silence-leglise-clandestine-en-iran\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/sans-silence-leglise-clandestine-en-iran\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2025\\\/05\\\/PRAYER-SAFE-scaled.jpg\",\"datePublished\":\"2025-05-07T04:21:27+00:00\",\"dateModified\":\"2026-08-25T16:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/sans-silence-leglise-clandestine-en-iran\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/sans-silence-leglise-clandestine-en-iran\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/sans-silence-leglise-clandestine-en-iran\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2025\\\/05\\\/PRAYER-SAFE-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2025\\\/05\\\/PRAYER-SAFE-scaled.jpg\",\"width\":1689,\"height\":3000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/apprendre\\\/sans-silence-leglise-clandestine-en-iran\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sans silence : L&#8217;\u00e9glise souterraine d&#8217;Iran\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/\",\"name\":\"Transform Iran\",\"description\":\"Bringing the love and power of Christ to Iran - and beyond\",\"publisher\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#organization\",\"name\":\"Transform Iran\",\"url\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2022\\\/11\\\/logo_grey.jpg\",\"contentUrl\":\"https:\\\/\\\/transformiran.com\\\/app\\\/uploads\\\/2022\\\/11\\\/logo_grey.jpg\",\"width\":528,\"height\":90,\"caption\":\"Transform Iran\"},\"image\":{\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/222MinistriesUSAInc\",\"https:\\\/\\\/x.com\\\/222minint\",\"https:\\\/\\\/www.instagram.com\\\/222ministriesinternational\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/#\\\/schema\\\/person\\\/901d817bcb841b949dbba5fa2886bfe3\",\"name\":\"Ashleigh Bedford\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g\",\"caption\":\"Ashleigh Bedford\"},\"url\":\"https:\\\/\\\/transformiran.com\\\/fr\\\/author\\\/ashleigh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sans silence : L'\u00e9glise souterraine d'Iran - Transform Iran","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/","og_locale":"fr_FR","og_type":"article","og_title":"Sans silence : L'\u00e9glise souterraine d'Iran - Transform Iran","og_description":"Curieux de savoir \u00e0 quoi ressemble vraiment la vie des croyants clandestins en Iran ? Cet article vous offre un aper\u00e7u de leur monde cach\u00e9.","og_url":"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/","og_site_name":"Transform Iran","article_publisher":"https:\/\/www.facebook.com\/222MinistriesUSAInc","article_published_time":"2025-05-07T04:21:27+00:00","article_modified_time":"2026-08-25T16:00:00+00:00","og_image":[{"width":1689,"height":3000,"url":"https:\/\/transformiran.com\/app\/uploads\/2025\/05\/PRAYER-SAFE-scaled.jpg","type":"image\/jpeg"}],"author":"Ashleigh Bedford","twitter_card":"summary_large_image","twitter_creator":"@222minint","twitter_site":"@222minint","twitter_misc":{"Written by":"Ashleigh Bedford","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/#article","isPartOf":{"@id":"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/"},"author":{"name":"Ashleigh Bedford","@id":"https:\/\/transformiran.com\/fr\/#\/schema\/person\/901d817bcb841b949dbba5fa2886bfe3"},"headline":"Sans silence : L&#8217;\u00e9glise souterraine d&#8217;Iran","datePublished":"2025-05-07T04:21:27+00:00","dateModified":"2026-08-25T16:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/"},"wordCount":1444,"commentCount":0,"publisher":{"@id":"https:\/\/transformiran.com\/fr\/#organization"},"image":{"@id":"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/#primaryimage"},"thumbnailUrl":"https:\/\/transformiran.com\/app\/uploads\/2025\/05\/PRAYER-SAFE-scaled.jpg","keywords":["\u00c9glise","\u00c9glise pers\u00e9cut\u00e9e","Formation de disciple","Gouvernement","Transformation"],"articleSection":["Apprendre"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/","url":"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/","name":"Sans silence : L'\u00e9glise souterraine d'Iran - Transform Iran","isPartOf":{"@id":"https:\/\/transformiran.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/#primaryimage"},"image":{"@id":"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/#primaryimage"},"thumbnailUrl":"https:\/\/transformiran.com\/app\/uploads\/2025\/05\/PRAYER-SAFE-scaled.jpg","datePublished":"2025-05-07T04:21:27+00:00","dateModified":"2026-08-25T16:00:00+00:00","breadcrumb":{"@id":"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/#primaryimage","url":"https:\/\/transformiran.com\/app\/uploads\/2025\/05\/PRAYER-SAFE-scaled.jpg","contentUrl":"https:\/\/transformiran.com\/app\/uploads\/2025\/05\/PRAYER-SAFE-scaled.jpg","width":1689,"height":3000},{"@type":"BreadcrumbList","@id":"https:\/\/transformiran.com\/fr\/apprendre\/sans-silence-leglise-clandestine-en-iran\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/transformiran.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Sans silence : L&#8217;\u00e9glise souterraine d&#8217;Iran"}]},{"@type":"WebSite","@id":"https:\/\/transformiran.com\/fr\/#website","url":"https:\/\/transformiran.com\/fr\/","name":"Transform Iran","description":"Bringing the love and power of Christ to Iran - and beyond","publisher":{"@id":"https:\/\/transformiran.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transformiran.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/transformiran.com\/fr\/#organization","name":"Transform Iran","url":"https:\/\/transformiran.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/transformiran.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/transformiran.com\/app\/uploads\/2022\/11\/logo_grey.jpg","contentUrl":"https:\/\/transformiran.com\/app\/uploads\/2022\/11\/logo_grey.jpg","width":528,"height":90,"caption":"Transform Iran"},"image":{"@id":"https:\/\/transformiran.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/222MinistriesUSAInc","https:\/\/x.com\/222minint","https:\/\/www.instagram.com\/222ministriesinternational\/"]},{"@type":"Person","@id":"https:\/\/transformiran.com\/fr\/#\/schema\/person\/901d817bcb841b949dbba5fa2886bfe3","name":"Ashleigh Bedford","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe25a0a0785840df62a592de76ed79e48013f590cc9a874b448f15b293751483?s=96&d=mm&r=g","caption":"Ashleigh Bedford"},"url":"https:\/\/transformiran.com\/fr\/author\/ashleigh\/"}]}},"_links":{"self":[{"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/posts\/30860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/comments?post=30860"}],"version-history":[{"count":1,"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/posts\/30860\/revisions"}],"predecessor-version":[{"id":40038,"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/posts\/30860\/revisions\/40038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/media\/40030"}],"wp:attachment":[{"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/media?parent=30860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/categories?post=30860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transformiran.com\/fr\/wp-json\/wp\/v2\/tags?post=30860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}